{"id":10033,"date":"2019-02-26T09:53:58","date_gmt":"2019-02-26T08:53:58","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=10033"},"modified":"2019-02-27T09:36:37","modified_gmt":"2019-02-27T08:36:37","slug":"cuentacuentos-musical-ipuinak-dantzan","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/cuentacuentos-musical-ipuinak-dantzan\/","title":{"rendered":"Cuentacuentos musical: \u00abIpuinak dantzan\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 23\/03\/2019, 18:30<br \/>\n<strong>D\u00f3nde:<\/strong> Lezaun. Ayuntamiento (Korrika Festa)<\/p>\n<p><strong>Edad:<\/strong> a partir de 4 a\u00f1os<\/p>\n<p>Se trata de una sesi\u00f3n donde la m\u00fasica y las palabras se acompa\u00f1an, se ceden turno, se divirten y danzan juntas. Con la guitarra electrica de Intxixu Valbuena cantaremos algunos temas de actualidad y otros de siempre, y Ana Apika narrar\u00e1 historias con acompa\u00f1amiento musical. Una sesi\u00f3n slow con humor para ni\u00f1os, ni\u00f1\u00e1s y acompa\u00f1antes.<\/p>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"&quot;IPUINAK DANTZAN&quot;. Museo Balenciaga. 2017\/08\/17. Intxixu Valbuena &amp; Ana Apika\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/BA-SlfGEu5s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 23\/03\/2019, 18:30<br \/>\n<strong>D\u00f3nde:<\/strong> Lezaun. Ayuntamiento<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[223],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-10033","class","type-class","status-publish","hentry","wcs-type-tierra-estella-tafalla-valdizarbe-puente-la-reina-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/10033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=10033"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=10033"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=10033"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=10033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}