{"id":10749,"date":"2019-04-01T11:24:04","date_gmt":"2019-04-01T09:24:04","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=10749"},"modified":"2019-04-08T11:26:22","modified_gmt":"2019-04-08T09:26:22","slug":"zinema-pirata-arratoia","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/zinema-pirata-arratoia\/","title":{"rendered":"Cine: \u00abPirata Arratoia\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 13\/04\/2019 \u2013 14\/04\/2019; ambas sesiones a las 17:00<br \/>\n<strong>D\u00f3nde:<\/strong> Estella-Lizarra. Cines Los Llanos<\/p>\n<p>\u00a1Cuidado con la rata pirata! El bandido m\u00e1s goloso de todos\u2026 Montado en su caballo, roba la comida de los viajeros que encuentra por el camino, hasta que un d\u00eda se cruza con alguien m\u00e1s astuto que \u00e9l\u2026 Un cuento de capa y espada, de ladrones y galletas.<\/p>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"ARRATOI PIRATA\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/YPffBhTGA_k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 13\/04\/2019 \u2013 14\/04\/2019; ambas sesiones a las 17:00<br \/>\n<strong>D\u00f3nde:<\/strong> Estella-Lizarra. Cines Los Llanos<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,223],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-10749","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-tierra-estella-tafalla-valdizarbe-puente-la-reina-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/10749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=10749"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=10749"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=10749"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=10749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}