{"id":14065,"date":"2019-10-25T18:14:43","date_gmt":"2019-10-25T16:14:43","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=14065"},"modified":"2019-10-25T18:14:43","modified_gmt":"2019-10-25T16:14:43","slug":"teatro-etxerik-txikiena-3","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/teatro-etxerik-txikiena-3\/","title":{"rendered":"Teatro: \u00abEtxerik txikiena\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 26\/10\/2019, 17:30<br \/>\n<strong>D\u00f3nde:<\/strong> Etxarri Aranatz. Casa de Cultura<\/p>\n<p><strong>Edad:<\/strong> mayores de 6 a\u00f1os<\/p>\n<p>Con una maleta, un peque\u00f1o manzano y el deseo de volver pronto, Bettina deja atr\u00e1s su hogar para descansar del ruido de las bombas y del miedo que provoca la guerra. Al llegar a su \u201cnueva casa\u201d, se da cuenta de que nada es como imaginaba. Norma, otra ni\u00f1a en igual situaci\u00f3n, ser\u00e1 quien la acompa\u00f1e en esta historia, construyendo entre ambas una amistad que les permitir\u00e1 hacer frente a las dificultades que van sobreviniendo.<\/p>\n<p><strong>Compa\u00f1\u00eda:<\/strong> Yarleku<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo: <\/strong>26\/10\/2019, 17:30<br \/>\n<strong>D\u00f3nde: <\/strong>Etxarri Aranatz. Casa de Cultura<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,229],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-14065","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-sakana-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/14065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=14065"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=14065"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=14065"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=14065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}