{"id":15185,"date":"2019-11-25T18:21:31","date_gmt":"2019-11-25T17:21:31","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=15185"},"modified":"2019-11-25T18:21:31","modified_gmt":"2019-11-25T17:21:31","slug":"cuentacuentos-potxa-eta-flobin-istorio-eta-ipuin-3","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/cuentacuentos-potxa-eta-flobin-istorio-eta-ipuin-3\/","title":{"rendered":"Cuentacuentos: \u00abPotxa eta Flobin istorio eta ipuin\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 05\/12\/2019, 18:00<br \/>\n<strong>D\u00f3nde:<\/strong> Tafalla. Casa de Cultura<\/p>\n<p>Euskarabidea. D\u00eda Internacional del Euskera<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 05\/12\/2019, 18:00<br \/>\n<strong>D\u00f3nde: <\/strong>Tafalla. Casa de Cultura<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[223],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-15185","class","type-class","status-publish","hentry","wcs-type-tierra-estella-tafalla-valdizarbe-puente-la-reina-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/15185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=15185"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=15185"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=15185"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=15185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}