{"id":16074,"date":"2020-01-09T13:28:58","date_gmt":"2020-01-09T12:28:58","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=16074"},"modified":"2020-01-09T13:31:04","modified_gmt":"2020-01-09T12:31:04","slug":"zinema-ardiak-eta-otsoak","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/zinema-ardiak-eta-otsoak\/","title":{"rendered":"Zinema: \u00abArdiak eta otsoak\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 12\/01\/2020, 16:30<br \/>\n<strong>D\u00f3nde:<\/strong> Lesaka. Casa de Cultura Harriondoa<\/p>\n<p><strong>Precio:<\/strong> 2 euros<\/p>\n<blockquote><p>En una tierra m\u00e1gica y lejana, en un peque\u00f1o y pintoresco pueblo situado entre verdes prados y colinas, vive un reba\u00f1o de ovejas sin preocupaciones. Pero su vida pastoral y libre de estr\u00e9s se interrumpe cuando una manada de lobos establece su campamento en el barranco cercano. De acuerdo con las tradiciones antiguas, el l\u00edder de la manada, Magra, anuncia que su futuro sucesor debe probar su derecho a liderar desbancando a sus rivales. Cuando el poderoso y sanguinario Ragear da un paso adelante, el \u00fanico lobo lo suficientemente valiente como para desafiarlo es Gris, el favorito de la manada, pero un mete patas sin esperanza.,Gris va al bosque, donde descubre un campamento de conejos gitanos. La adivina conejo le da una m\u00e1gica poci\u00f3n de la transmutaci\u00f3n. Gris la bebe poci\u00f3n y regresa a la cueva de los lobos, pero descubre a su llegada que ya no es otro de ellos. Ahora se ha transformado \u00a1en una oveja!<\/p><\/blockquote>\n<p><strong>Organiza:<\/strong> Asociaciones de madres y padres de la Ikastola Tantirumairu y la Escuela P\u00fablica Irain<\/p>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"ARDIAK ETA OTSOAK\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ecDWuGde9WI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo: <\/strong>12\/01\/2020, 16:30<br \/>\n<strong>D\u00f3nde: <\/strong>Lesaka. Casa de Cultura Harriondoa<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[202],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-16074","class","type-class","status-publish","hentry","wcs-type-bortziriak-baztan-malerreka-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/16074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=16074"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=16074"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=16074"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=16074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}