{"id":16826,"date":"2020-02-05T12:42:16","date_gmt":"2020-02-05T11:42:16","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=16826"},"modified":"2020-02-05T12:42:16","modified_gmt":"2020-02-05T11:42:16","slug":"cine-ozzy","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/cine-ozzy\/","title":{"rendered":"Cine: \u00abOzzy\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 16\/02\/2020. 16:30<br \/>\n<strong>D\u00f3nde:<\/strong> Lesaka. Harriondoa Kultur Etxea<\/p>\n<blockquote><p>La id\u00edlica vida de Ozzy, un simp\u00e1tico y pac\u00edfico beagle que se ha criado entre algodones junto a la familia Martin, va a dar un vuelco. Cuando su familia no puede llevarle a un largo viaje lejos de su hogar, le depositan en lo que creen que es el mejor balneario canino, Blue Creek. Pero la perfecta estampa del lugar resulta ser una fachada urdida por su villano propietario, y otro destino bien distinto aguarda a Ozzy: \u00e9ste ir\u00e1 pronto a parar al verdadero Blue Creek, una c\u00e1rcel para perros, habitada en su mayor\u00eda por duros chuchos callejeros y donde prevalece la ley del m\u00e1s fuerte. All\u00ed dentro, Ozzy tendr\u00e1 que esquivar el peligro, encontrar fuerzas donde no cre\u00eda tenerlas y aprender a apoyarse en Chester, Fronky y Doc, los nuevos amigos que le acompa\u00f1ar\u00e1n en esta aventura para intentar regresar sano y salvo.<\/p><\/blockquote>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"OZZY TRAILER EUSKARA ZINEUSKADI 24FPS ALTA\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/pnPhQWVcb2A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo: <\/strong>16\/02\/2020. 16:30<br \/>\n<strong>D\u00f3nde:<\/strong> Lesaka. Harriondoa Kultur Etxea<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,202],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-16826","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-bortziriak-baztan-malerreka-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/16826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=16826"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=16826"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=16826"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=16826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}