{"id":17106,"date":"2020-02-20T14:24:08","date_gmt":"2020-02-20T13:24:08","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=17106"},"modified":"2020-02-20T14:40:36","modified_gmt":"2020-02-20T13:40:36","slug":"cine-lur-eta-amets-4","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/cine-lur-eta-amets-4\/","title":{"rendered":"Cine: \u00abLur eta Amets\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 22\/02\/2020 a las 17:15 y 23\/02\/2020 a las 17:30<br \/>\n<strong>D\u00f3nde:<\/strong> Estella-Lizarra. Centro Cultural Los Llanos<\/p>\n<p><strong>Duraci\u00f3n:<\/strong> 87 min.<\/p>\n<blockquote><p><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">Los padres de Lur y Amets tienen una boda este fin de semana y los gemelos pasar\u00e1n unos d\u00edas en casa de la abuela Andere. Pero g<\/span><\/span><span class=\"tlid-translation translation\" lang=\"es\"><span class=\"\" title=\"\">racias a los poderes de Andere y su gato Baltaxar, este no ser\u00e1 un fin de semana normal.<\/span> <span class=\"\" title=\"\">Se embarcar\u00e1n en un viaje, experimentando aventuras agridulces en diferentes momentos y \u00e9pocas, viajando a lo largo de nuestra historia.<\/span> <span class=\"\" title=\"\">Siempre ser\u00e1n los protagonistas, con la inestimable ayuda de Andere y Baltaxar.<\/span> <span class=\"\" title=\"\">Pero, por desgracia, no se podr\u00e1n librar facilmente de los malvados.<\/span><\/span><\/p><\/blockquote>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"Lur eta Amets filma - Trailer\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9ZeEub_WG54?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 22\/02\/2020, 17:15 y 23\/02\/2020, 17:30<br \/>\n<strong>D\u00f3nde:<\/strong> Estella-Lizarra. Centro Cultural Los Llanos<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[223],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-17106","class","type-class","status-publish","hentry","wcs-type-tierra-estella-tafalla-valdizarbe-puente-la-reina-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/17106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=17106"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=17106"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=17106"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=17106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}