{"id":17845,"date":"2020-04-03T08:00:54","date_gmt":"2020-04-03T06:00:54","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=17845"},"modified":"2021-03-05T07:57:09","modified_gmt":"2021-03-05T06:57:09","slug":"ene-kantak-ausartak","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/ene-kantak-ausartak\/","title":{"rendered":"Ene Kantak: \u00abAusartak\u00bb"},"content":{"rendered":"<p style=\"text-align: right;\"><em>Mientras no podamos ir a las salas de cine o teatro ni a las bibliotecas, <strong>era.eus<\/strong> te acercar\u00e1 todos los d\u00edas una propuesta cultural: cuentos, canciones, teatro, dibujos animados, juegos\u2026<\/em><\/p>\n<p>Las <strong>canciones y coreograf\u00edas<\/strong> de <a href=\"https:\/\/enekantak.org\/es\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Ene Kantak<\/a> han conseguido una conexi\u00f3n especial con las ni\u00f1as y los ni\u00f1os. \u00abAusartak\u00bb no es m\u00e1s que un ejemplo de la lista de \u00e9xitos del grupo:<\/p>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"Ene Kantak - Ausartak\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/r6QNLYxaG4s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>Si una canci\u00f3n no es suficiente, el v\u00eddeo del <strong>espect\u00e1culo \u00abJai Erraldoia\u00bb<\/strong> grabado en el Navarra Arena de Pamplona el 29 de diciembre de 2018 puede remediarlo:<\/p>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"ENE KANTAK JAI ERRALDOIA 2018 SATORJATOR\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/DDSb21IFaEU?start=32&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>Y de lunes a viernes se pueden ver los programas de Ene Kantak en el <a href=\"https:\/\/www.eitb.eus\/eu\/hiru3\/3enekantak\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">canal de televisi\u00f3n ETB3<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong> V\u00eddeos del grupo Ene Kantak <\/strong><\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[233],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-17845","class","type-class","status-publish","hentry","wcs-type-otros-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/17845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=17845"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=17845"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=17845"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=17845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}