{"id":19899,"date":"2020-07-09T08:45:41","date_gmt":"2020-07-09T06:45:41","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=19899"},"modified":"2020-08-06T09:14:24","modified_gmt":"2020-08-06T07:14:24","slug":"teatro-etxerik-txikiena-7","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/teatro-etxerik-txikiena-7\/","title":{"rendered":"Teatro: \u00abEtxerik txikiena\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 20\/09\/2020; horario por se\u00f1alar.<br \/>\n<strong>D\u00f3nde:<\/strong> Olazti. Lugar por definir<br \/>\n<strong>Edad recomendada:<\/strong> 4-10 a\u00f1os<\/p>\n<p>Duraci\u00f3n: 50&#8242;<\/p>\n<p>Con una maleta, un peque\u00f1o manzano y el deseo de volver pronto, Bettina deja atr\u00e1s su hogar para descansar del ruido de las bombas y del miedo que provoca la guerra.<br \/>\nEste montaje aborda la incertidumbre de los ni\u00f1os y ni\u00f1as refugiados tras abandonar su lugar de origen, el desarraigo y la importancia de los v\u00ednculos en estas situaciones.<br \/>\nSi un hogar es el lugar donde habitamos con sensaci\u00f3n de seguridad y calma, \u00bfcu\u00e1l es la unidad m\u00ednima para ello? Tal vez un abrazo pueda ser la casa m\u00e1s peque\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 20\/09\/2020; horario por definir<br \/>\n<strong>D\u00f3nde:<\/strong> Olazti. Lugar por definir<br \/>\n<strong>Edad recomendada:<\/strong> 4-10 a\u00f1os<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,229],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-19899","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-sakana-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/19899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=19899"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=19899"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=19899"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=19899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}