{"id":19946,"date":"2020-07-10T19:53:46","date_gmt":"2020-07-10T17:53:46","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=19946"},"modified":"2020-07-17T08:42:29","modified_gmt":"2020-07-17T06:42:29","slug":"cine-abentura-historiaurrean-3","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/cine-abentura-historiaurrean-3\/","title":{"rendered":"Cine: \u00abAbentura historiaurrean\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 17 &#8211; 23\/07\/2020, 17:15<br \/>\n<strong>D\u00f3nde:<\/strong> Galar. Golem Morea<\/p>\n<p><strong>Iraupena:<\/strong> 90 min.<\/p>\n<blockquote><p>Boonie Bears: Blast into the past (Boonie Bears: Blast into the past). Vick y los osos se encuentran atrapados en el pasado, rodeados de gigantescos animales que parecen tener una sola cosa en mente: \u00a1\u00a1EL ALMUERZO!! Cuando nuestros h\u00e9roes se separan, Briar se encuentra con un joven LOBO llamado FEIFEI, que tiene la intenci\u00f3n de convertirse en un valiente guerrero. Mientras tanto, Bramble y Vick tienen sus propios problemas, lo que incluye\u2026\u00a1\u00a1\u00a1 Una aventura como la que nunca se hab\u00edan enfrentado antes!!!<\/p><\/blockquote>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"Abentura historiaurrean\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/fDdwnCbDplc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 17 &#8211; 23\/07\/2020, 17:15<br \/>\n<strong>D\u00f3nde:<\/strong> Galar. Golem Morea<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[219,338],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-19946","class","type-class","status-publish","hentry","wcs-type-baranain-zizur-mayor-orkoien-galar-olza-etxauri-es","wcs-type-comarca-pamplona","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/19946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=19946"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=19946"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=19946"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=19946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}