{"id":20853,"date":"2020-10-06T13:34:39","date_gmt":"2020-10-06T11:34:39","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=20853"},"modified":"2020-10-12T00:31:19","modified_gmt":"2020-10-11T22:31:19","slug":"kaleko-jolasak-euskaraz","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/kaleko-jolasak-euskaraz\/","title":{"rendered":"Juegos dinamizados en la calle"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 13\/10\/2020, 17:00-18:30<br \/>\n<strong>D\u00f3nde:<\/strong> Artica. Plaza central (calle Mar\u00eda Dominguez)<br \/>\n<strong>Edad:<\/strong> de 6 a\u00f1os en adelante.<br \/>\n<strong>Precio:<\/strong> Gratuito<br \/>\n<strong>Inscripci\u00f3n: <\/strong>7 al 9 de octubre \u00a0de octubre, en el tel. 012. Para participar es <strong>obligatorio<\/strong> inscribirse previamente.<\/p>\n<p>Juegos dinamizados en la calle, de la mano de la Fundaci\u00f3n DINDAIA. El n\u00famero de ni\u00f1os\/as participantes estar\u00e1 limitado y se tendr\u00e1n en cuenta las medidas adoptadas en relaci\u00f3n al COVID.<\/p>\n<p>Actividad organizada por el Ayuntamiento de Berrioplano, dentro del <a href=\"http:\/\/www.berrioplano.es\/ciclo-euskera\/\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Ciclo Euskera<\/strong><\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong>  13\/10\/2020, 17:00-18:30<br \/>\n<strong>D\u00f3nde:<\/strong> Artica. Plaza central (calle Mar\u00eda Dominguez)<br \/>\n<strong>Inscripci\u00f3n:<\/strong> 7 al 9 de octubre \u00a0de octubre, en el tel. 012.<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[221,338],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-20853","class","type-class","status-publish","hentry","wcs-type-ansoain-berriozar-berrioplano-es","wcs-type-comarca-pamplona","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/20853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=20853"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=20853"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=20853"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=20853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}