{"id":28885,"date":"2021-11-11T11:31:18","date_gmt":"2021-11-11T10:31:18","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=28885"},"modified":"2021-11-11T11:31:18","modified_gmt":"2021-11-11T10:31:18","slug":"cuentacuentos-y-taller-liburutegi-ibiltaria-2","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/cuentacuentos-y-taller-liburutegi-ibiltaria-2\/","title":{"rendered":"Cuentacuentos y taller: Liburutegi ibiltaria"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 01\/12\/2021, 17:00h<br \/>\n<strong>D\u00f3nde:<\/strong> Allo. Biblioteca<\/p>\n<p><strong>Edad:<\/strong> 3-12 a\u00f1os<br \/>\n<strong>Duraci\u00f3n:<\/strong> 60 min.<\/p>\n<p>D\u00e9jate sorprender con la <strong><em>Biblioteca m\u00f3vil<\/em><\/strong>. Cuentos en euskera para ni\u00f1os y ni\u00f1as de edades comprendidas entre los 3 y los 15 a\u00f1os se pondr\u00e1n a disposici\u00f3n de las personas asistentes. Ir\u00e1 precedido de una sesi\u00f3n de cuentos en la que de una manera divertida y participativa se fomentar\u00e1 la lectura, la igualdad, la tolerancia y el respeto. Cojines, colchonetas, esterillas, mantas\u2026 Buscaremos transformar el espacio en un lugar agradable, relajado y divertido para que los ni\u00f1os y ni\u00f1as, junto a sus familias, puedan disfrutar leyendo juntos.<\/p>\n<p><a href=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2021\/11\/Allo-liburutegi-ibiltaria.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2021\/11\/Allo-liburutegi-ibiltaria-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" class=\"alignleft size-medium wp-image-28876\" srcset=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2021\/11\/Allo-liburutegi-ibiltaria-212x300.jpg 212w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2021\/11\/Allo-liburutegi-ibiltaria.jpg 542w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 01\/12\/2021, 17:00h<br \/>\n<strong>D\u00f3nde:<\/strong> Allo. Biblioteca<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,233,223],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-28885","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-otros-es","wcs-type-tierra-estella-tafalla-valdizarbe-puente-la-reina-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/28885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=28885"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=28885"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=28885"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=28885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}