{"id":36863,"date":"2022-10-28T19:57:13","date_gmt":"2022-10-28T17:57:13","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=36863"},"modified":"2022-11-03T08:19:27","modified_gmt":"2022-11-03T07:19:27","slug":"teatro-tailoviu-4","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/teatro-tailoviu-4\/","title":{"rendered":"Teatro: \u00abTailoviu\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 19\/11\/2022, 17:30 h<br \/>\n<strong>D\u00f3nde:<\/strong> Carcastillo. Sala de cine<\/p>\n<p>El enamoramiento infantil no s\u00f3lo existe sino que es muy frecuente en ni\u00f1os y ni\u00f1as peque\u00f1os y se trata de una emoci\u00f3n que debe ser abordada desde la empat\u00eda y el respeto. Este es un momento estupendo para desmitificar el amor rom\u00e1ntico.<\/p>\n<p>Que las ni\u00f1as act\u00faen como princesas y los ni\u00f1os como guerreros no se trata solo de un inocente juego de infancia. Es m\u00e1s bien una creencia en la que la sociedad ha basado la idea de amor rom\u00e1ntico y que reproducen los seres humanos en todas las etapas de la vida.<\/p>\n<p>Podemos Prevenir la violencia machista en edades tempranas. Estos patrones generan sufrimiento porque no son reales y debe ense\u00f1arse el amor desde el respeto, el reconocimiento del otro y la aceptaci\u00f3n de la diferencia.<\/p>\n<p>Amar es respetar<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 19\/11\/2022, 17:30 h<br \/>\n<strong>D\u00f3nde:<\/strong> Carcastillo. Sala de cine<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,233],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-36863","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-otros-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/36863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=36863"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=36863"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=36863"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=36863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}