{"id":38335,"date":"2023-01-12T10:53:11","date_gmt":"2023-01-12T09:53:11","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=38335"},"modified":"2023-01-12T10:54:54","modified_gmt":"2023-01-12T09:54:54","slug":"taller-familiar-desayunos-y-meriendas-saludables-y-sostenibles","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/taller-familiar-desayunos-y-meriendas-saludables-y-sostenibles\/","title":{"rendered":"Taller familiar: desayunos y meriendas saludables y sostenibles"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p><strong>Cu\u00e1ndo:<\/strong> 15\/03\/2023, 17:30<\/p>\n<p><strong>D\u00f3nde: <\/strong>Pamplona. Museo de Educaci\u00f3n Ambiental (C\/Errotazar, 21 bis) <strong><br \/>\nPrecio: <\/strong>gratuito<strong><br \/>\n<\/strong><\/p>\n<p><strong>Inscripci\u00f3n: <\/strong>a partir del 1 de marzo llamando 010 o\u0301 948 42 01 00.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"vc_row wpb_row vc_row-fluid\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"page\" title=\"Page 23\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>La alimentacio\u0301n infantil es uno de los condicionantes de la calidad de vida, no solo actual sino de la infancia en el futuro. Con la mirada puesta en el camino hacia una alimentacio\u0301n infantil ma\u0301s saludable y sostenible, se presentan los talleres de desayunos y meriendas.<\/p>\n<p>Se trata de un formato de taller pra\u0301ctico en el que las familias puedan realizar sencillas elaboraciones mientras se habla de nutricio\u0301n en un ambiente distendido y tranquilo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo<\/strong> 15\/03\/2023, 17:30-19:00<br \/>\n<strong>D\u00f3nde:<\/strong> Pamplona. Museo Educaci\u00f3n Ambiental<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[338,227],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-38335","class","type-class","status-publish","hentry","wcs-type-comarca-pamplona","wcs-type-pamplona-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/38335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=38335"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=38335"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=38335"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=38335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}