{"id":40637,"date":"2023-04-28T14:43:02","date_gmt":"2023-04-28T12:43:02","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=40637"},"modified":"2023-05-02T11:14:15","modified_gmt":"2023-05-02T09:14:15","slug":"dia-del-euskera","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/dia-del-euskera\/","title":{"rendered":"D\u00eda del Euskera"},"content":{"rendered":"<p><strong>\u00bfCu\u00e1ndo?:<\/strong> 2023\/05\/06<\/p>\n<p><strong>\u00bfD\u00f3nde?:<\/strong> Zolinan. Aranguren Ibarra.<\/p>\n<p><b>Egitaraua:<\/b><\/p>\n<p>11:30: Actuaci\u00f3n de los gigantes y la Comparsa del Valle de Aranguren.<\/p>\n<p>12:30: Juegos para todas las edades.<\/p>\n<p>13:30: Actuaci\u00f3n de los dantzaris txikis del Valle de Aranguren.<\/p>\n<p>14:00: Trikipoteo y txistorrada.<\/p>\n<p>15:00: Comida autogestionada (1\u20ac\/persona) y popular (adultos 24\u20ac \/ni\u00f1os y ni\u00f1as 12\u20ac). Para la compra de los tickets hay tres lugares (Aranetxea, Servicio de Euskera y Casa de Cultura) <strong>hasta el 2 de mayo. <\/strong><\/p>\n<p>16:00: Sesi\u00f3n de tikitixas.<\/p>\n<p>16:30: Talleres infantiles: juegos en la naturaleza, decoraci\u00f3n de calles, circo, juegos gigantes y disco fiesta.<\/p>\n<p>19:00: Txaranga.<\/p>\n<p>21:00: Bocatas. (Tickets a la venta en 3 lugares como los de la comida).<\/p>\n<p>22:00: DJ Jotatxo (hasta las 02:00).<\/p>\n<p>Toda la informaci\u00f3n aqu\u00ed: <a href=\"https:\/\/www.aranguren.es\/eventos\/dia-del-euskera-en-zolina-2023\/\" rel=\"nofollow noopener\" target=\"_blank\">D\u00cdA DEL EUSKERA EN ZOLINA 2023 \u2013 Ayuntamiento del Valle de Aranguren<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>\u00bfCu\u00e1ndo?: <\/strong> 2023\/05\/06<br \/>\n<strong>\u00bfD\u00f3nde?: <\/strong>Zolinan. Aranguren Ibarra.<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[225],"wcs-room":[441],"wcs-instructor":[214],"class_list":["post-40637","class","type-class","status-publish","hentry","wcs-type-valle-de-egues-aranguren-es","wcs-room-aranguren-ibarra","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/40637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=40637"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=40637"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=40637"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=40637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}