{"id":41494,"date":"2023-06-16T10:24:20","date_gmt":"2023-06-16T08:24:20","guid":{"rendered":"https:\/\/eranafarroa.eus\/eranafarroa\/inscripcion-abierta-talleres-de-verano-de-biltoki-2\/"},"modified":"2023-06-16T10:25:47","modified_gmt":"2023-06-16T08:25:47","slug":"inscripcion-abierta-talleres-de-verano-de-biltoki-2","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/inscripcion-abierta-talleres-de-verano-de-biltoki-2\/","title":{"rendered":"\u00daltimo d\u00eda de inscripci\u00f3n: talleres de verano de Biltoki"},"content":{"rendered":"<p><strong>Cu\u00e1ndo: <\/strong>26-27-28-29- 30 de junio<\/p>\n<p><strong>D\u00f3nde:<\/strong> Pamplona. Biltoki (Txantrea)<\/p>\n<p><strong>Horario:\u00a0<\/strong>Las sesiones ser\u00e1n de 11:00 a 13:00. Si hay mucha inscripci\u00f3n, se har\u00e1n dos grupos, de 10:00 a 12:00 y de 12:15 a 14:15.<\/p>\n<p><strong><br \/>\nPrecio:<\/strong> 4\u20ac cada d\u00eda, en caso de que venga los 5 d\u00edas 16\u20ac euros. Se pagar\u00e1 en mano, a poder ser el primer d\u00eda.<\/p>\n<p>Inscripci\u00f3n: hasta el 22 dejunio<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> del 26 al 30 (inscripci\u00f3n hasta el 22).<br \/>\n<strong>D\u00f3nde:<\/strong> Pamplona. Asociaci\u00f3n Biltoki, Txantrea<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[338,227],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-41494","class","type-class","status-publish","hentry","wcs-type-comarca-pamplona","wcs-type-pamplona-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/41494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=41494"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=41494"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=41494"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=41494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}