{"id":42124,"date":"2023-08-22T13:41:27","date_gmt":"2023-08-22T11:41:27","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=42124"},"modified":"2023-08-22T13:41:27","modified_gmt":"2023-08-22T11:41:27","slug":"canta-cuentos-3","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/canta-cuentos-3\/","title":{"rendered":"Canta cuentos"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong>\u00a02023\/11\/10, 17:00 \u2013 18:00<br \/>\n<strong>D\u00f3nde:<\/strong>\u00a0Mutilva. Auditorio de la Casa de Cultura del Valle de Aranguren (Plaza Eguzki)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Edad:<\/strong>\u00a0A partir de 4 a\u00f1os<br \/>\n<strong>Precio:<\/strong>\u00a0Gratuito<\/p>\n<p><strong>Artistas:\u00a0<\/strong>Musas y Fusas<\/p>\n<p><strong>Organiza:<\/strong>\u00a0Departamento de Cultura<br \/>\nTel. 948291489<br \/>\n<a href=\"mailto:c.culturarecepcion@gmail.com\" target=\"_blank\" rel=\"noopener\">c.culturarecepcion@gmail.com<\/a><\/p>\n<p>Nota: Se agradece llegar a tiempo<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:\u00a0<\/strong>2023\/11\/10, 17:00 \u2013 18:00<br \/>\n<strong>D\u00f3nde:\u00a0<\/strong>Mutilva. Auditorio de la Casa de Cultura del Valle de Aranguren (Plaza Eguzki)<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,225],"wcs-room":[441],"wcs-instructor":[214,421,445],"class_list":["post-42124","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-valle-de-egues-aranguren-es","wcs-room-aranguren-ibarra","wcs-instructor-era","wcs-instructor-familiak","wcs-instructor-ipuin-kantariak"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/42124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=42124"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=42124"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=42124"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=42124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}