{"id":43711,"date":"2023-10-27T08:58:50","date_gmt":"2023-10-27T06:58:50","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=43711"},"modified":"2023-10-27T08:58:50","modified_gmt":"2023-10-27T06:58:50","slug":"pintacaras-gau-beltza","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/pintacaras-gau-beltza\/","title":{"rendered":"Pintacaras: Gau Beltza"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 31\/10\/2023, 16:30 h<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor. Cubierto rojo Erreniega.<\/p>\n<p>La cultura anglosajona lo denomina <em>Halloween<\/em>. En latinoamerica celebran el <em>D\u00eda de los Muertos<\/em>. Nuestros y nuestras aitatxi-amatxis lo denominaron de diversas formas, como por ejemplo la <em>Noche de \u00c1nimas<\/em>, (\u00bfQuieres saber m\u00e1s? \u00ab<a href=\"https:\/\/eranafarroa.eus\/es\/calabazas-y-txinurris-para-dar-comienzo-al-invierno\/\">Calabazas y \u201ctxinurris\u201d para dar comienzo al invierno<\/a>\u00bb). <strong>E<u>ste martes d\u00eda 31<\/u><\/strong> tenemos una propuesta, <strong><u>a las 16:30 h en el cubierto rojo de Erreniega<\/u><\/strong>, sesi\u00f3n de pintacaras para los ni\u00f1os y las ni\u00f1as que quieran donde se maquillar\u00e1 con la <a href=\"https:\/\/www.youtube.com\/watch?v=MQwi867hanc\" rel=\"nofollow noopener\" target=\"_blank\">est\u00e9tica de <em>Gau Beltza<\/em><\/a>. Ejercer\u00e1n de pintacaras padres y madres voluntarias de Erreniega y monitoras de Dindaia.<\/p>\n<p><strong>Y t\u00fa, como padre o madre<\/strong>, \u00bfquieres hacer algo m\u00e1s antes del martes? Por ejemplo, puedes preparar una calabaza casera con tu hija o hijo (aqu\u00ed un <a href=\"https:\/\/youtu.be\/GukDHlgC7tE?si=yAaatBT42J_gpu4U\" rel=\"nofollow noopener\" target=\"_blank\">taller de cabalabazas<\/a> en youtube; est\u00e1 en euskera, pero es muy gr\u00e1fico), pod\u00e9is escuchar el <a href=\"https:\/\/www.youtube.com\/watch?v=Dt84d8hiR_U\" rel=\"nofollow noopener\" target=\"_blank\">cuento de miedo<\/a> de <em>Gau Beltza<\/em>, o tambi\u00e9n la audio-serie <em>Hotzikarak<\/em> (escalofrios) accesible desde estre otro art\u00edculo de ERA.EUS: \u00ab<a href=\"https:\/\/eranafarroa.eus\/es\/noche-de-halloween-en-euskera\/\">Noche de Halloween en euskera<\/a>\u00bb. Son audio-cuentos de miedo para edades de 10-12 a\u00f1os.<\/p>\n<p>Por \u00faltimo, \u00bfsabes algo de euskera, quieres aprender a pintar caras y participar en la sesi\u00f3n como pintacaras este martes? Inf\u00f3rmate en el servicio de euskera: <a href=\"mailto:euskara@zizurnagusia.eus\">euskara@zizurnagusia.eus<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 31\/10\/2023, 16:30 h<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor. Cubierto rojo Erreniega.<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[219,338],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-43711","class","type-class","status-publish","hentry","wcs-type-baranain-zizur-mayor-orkoien-galar-olza-etxauri-es","wcs-type-comarca-pamplona","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/43711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=43711"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=43711"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=43711"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=43711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}