{"id":43781,"date":"2023-10-30T09:45:58","date_gmt":"2023-10-30T08:45:58","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=43781"},"modified":"2023-10-30T09:45:58","modified_gmt":"2023-10-30T08:45:58","slug":"gau-beltza-fotocol-pintacaras-kalejira-musica-dantza-txokolatada","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/gau-beltza-fotocol-pintacaras-kalejira-musica-dantza-txokolatada\/","title":{"rendered":"Gau Beltza: fotocol, pintacaras, kalejira, musica, dantza, txokolatada&#8230;"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 31\/10\/2023, 18:00 h<br \/>\n<strong>D\u00f3nde:<\/strong> Estella-Lizarra. Ikastola y plaza de Santiago<br \/>\n<strong>Programa:<\/strong><\/p>\n<ul>\n<li>18:00 h <strong>fotokol y pintacaras<\/strong>.<\/li>\n<li>18:30 h <strong>kalejira<\/strong> desde la Ikastola a la plaza de Santiago.<\/li>\n<li>19:00 h <strong>m\u00fasica, dantza, salto de calabazas y txokolatada<\/strong> en la plaza de Santiago.<\/li>\n<\/ul>\n<p>Y antes del martes, \u00bfqu\u00e9 podemos hacer? Aqu\u00ed dos propuestas:<\/p>\n<ol>\n<li>Apaga la luz, deja que la tr\u00e9mula luz de las farolas alumbre a trav\u00e9s de las cortinas, temblerosa, y <strong>escuchad los audio-cuentos<\/strong> <strong><em>Hotzikarak<\/em> <\/strong>(escalofr\u00edos). Accesibles desde el art\u00edculo de ERA.EUS \u201c<a href=\"https:\/\/eranafarroa.eus\/es\/noche-de-halloween-en-euskera\/\" target=\"_blank\" rel=\"noopener\">Noche de Halloween en euskera<\/a>\u201d.<\/li>\n<li>Recoge una calabaza de la huerta o la fruter\u00eda, y dale forma de Gau Beltza con los y las peques de casa. \u00a1Preparadla para el martes! Aqu\u00ed <strong>el video de taller de calabazas de Beltza:<\/strong><\/li>\n<\/ol>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"Gau Beltza   KALABAZA Tailerra\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/GukDHlgC7tE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><strong>Antolatzailea:<\/strong> Lizarra Ikastola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 31\/10\/2023, 18:00 h<br \/>\n<strong>D\u00f3nde:<\/strong> Estella-Lizarra. Ikastola y plaza de Santiago<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[223],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-43781","class","type-class","status-publish","hentry","wcs-type-tierra-estella-tafalla-valdizarbe-puente-la-reina-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/43781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=43781"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=43781"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=43781"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=43781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}