{"id":43949,"date":"2023-11-02T12:45:47","date_gmt":"2023-11-02T11:45:47","guid":{"rendered":"https:\/\/eranafarroa.eus\/eranafarroa\/sesion-de-cuentacuentos-liburu-sendalaria-2-2-2\/"},"modified":"2023-11-02T12:48:05","modified_gmt":"2023-11-02T11:48:05","slug":"sesion-de-cuentacuentos-liburu-sendalaria-2-2-2","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/sesion-de-cuentacuentos-liburu-sendalaria-2-2-2\/","title":{"rendered":"Sesi\u00f3n de cuentacuentos: \u00abLiburu sendalaria\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 03\/12\/2023, 18:30<\/p>\n<p><strong>D\u00f3nde:<\/strong> Monreal. Centro<\/p>\n<p><strong>Edad:<\/strong> p\u00fablico familiar<\/p>\n<p><strong>Organiza:<\/strong> Euskarabidea y Ayuntamiento de Monreal<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 03\/12\/2023, 18:30<br \/>\n<strong>D\u00f3nde:<\/strong> Monreal. Centro<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,233],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-43949","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-otros-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/43949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=43949"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=43949"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=43949"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=43949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}