{"id":44458,"date":"2023-11-15T09:54:51","date_gmt":"2023-11-15T08:54:51","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=44458"},"modified":"2023-11-15T09:54:51","modified_gmt":"2023-11-15T08:54:51","slug":"programa-de-radio-desde-el-colegio-ezkaba","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/programa-de-radio-desde-el-colegio-ezkaba\/","title":{"rendered":"Programa de radio desde el colegio Ezkaba"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 17 de noviembre<\/p>\n<p><strong>D\u00f3nde:<\/strong> 98,3 fm., Ansoain. Colegio Ezkaba<\/p>\n<p><strong>Horario:<\/strong> 9:00 &#8211; 11:00<\/p>\n<p>El programa matinal de Euskalerria Irratia se emitir\u00e1 desde el colegio Ezkaba.<\/p>\n<p>El alumnado participar\u00e1 en la realizaci\u00f3n del programa, en el que se entrevistar\u00e1n a personas ilustres de la localidad de Ans\u00f3ain.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 17 de noviembre<\/p>\n<p><strong>D\u00f3nde:<\/strong> 98,3 fm., Ansoain. Colegio Ezkaba<\/p>\n<p><strong>Horario:<\/strong> 9:00 &#8211; 11:00<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,221],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-44458","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-ansoain-berriozar-berrioplano-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/44458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=44458"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=44458"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=44458"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=44458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}