{"id":47078,"date":"2024-04-26T13:00:31","date_gmt":"2024-04-26T11:00:31","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=47078"},"modified":"2026-05-20T14:27:41","modified_gmt":"2026-05-20T12:27:41","slug":"zizur-deporte-euskera","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/zizur-deporte-euskera\/","title":{"rendered":"Inscripci\u00f3n: temporada deportiva Zizur 2026-2027"},"content":{"rendered":"<p><strong>Suma deporte y euskera. Multiplica emociones, experiencias y salud. Aunando deporte y euskera hacemos m\u00e1s Zizur.<\/strong><\/p>\n<p><strong>Oferta en euskera para la temporada 2026-2027 <\/strong>(inicio de los cursos el 1 de octubre de 2026):<\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #d3dba7;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\"><strong>INFANTIL<\/strong><\/p>\n<ul>\n<li><strong>Psicomotricidad<\/strong> (4-5 a\u00f1os, 94 \u20ac): lunes 16:45 \u2013 18:15<\/li>\n<li><strong>Nataci\u00f3n<\/strong> (90 \u20ac):\n<ul>\n<li>Ni\u00f1os y ni\u00f1as de 2020: martes 17:45 \u2013 18:15<\/li>\n<li>Ni\u00f1as y ni\u00f1os de 2021: lunes 17:15 \u2013 17:45 o martes 16:45 \u2013 17:15<\/li>\n<li>Ni\u00f1os y ni\u00f1as de 2022: lunes 16:45 \u2013 17:15 o martes 17:15 \u2013 17:45<\/li>\n<\/ul>\n<\/li>\n<li><strong>Multideporte<\/strong> (6-9 a\u00f1os, 114 \u20ac): lunes + jueves, 17:00 \u2013 18:00<\/li>\n<li><strong>Escalada<\/strong> (146 \u20ac):\n<ul>\n<li>7-10 a\u00f1os: lunes 17:00 \u2013 18:00<\/li>\n<li>11-14 a\u00f1os: mi\u00e9rcoles 17:00 \u2013 18:00<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong>ADOLESCENTES, J\u00d3VENES Y PERSONAS ADULTAS<\/strong><\/p>\n<ul>\n<li><strong>Ziklo Indoor<\/strong> (+14 urte, 100 \u20ac): lunes 17:45 \u2013 18:45<\/li>\n<li><strong>Entrenamiendo de fuerza para adolescentes<\/strong> (15-18 a\u00f1os, 180 \u20ac): martes + jueves 16:30 &#8211; 17:30<\/li>\n<li><strong>Escalada<\/strong> (+15 a\u00f1os, 226 \u20ac): mi\u00e9rcoles 18:00 \u2013 19:30<\/li>\n<li><strong>Zumba<\/strong> (+15 a\u00f1os, 90 \u20ac): martes\u00a015:15 &#8211; 16:15<\/li>\n<li><strong>Fit Boots<\/strong> (+16 a\u00f1os, 90 \u20ac): martes 19:00 &#8211; 20:00<\/li>\n<\/ul>\n<p>Todos los cursos se desarrollan en las instalaciones deportivas centrales de Zizur Mayor salvo escalada, que es en Patxi Morentin.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Plazos de inscripci\u00f3n<\/strong><strong>:<\/strong><\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #d3dba7;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\">\n<ul>\n<li><a href=\"https:\/\/www.zizurmayor.es\/servicios-municipales\/deportes\/\" target=\"_blank\" rel=\"noopener nofollow\"><strong>Mediante APP y Web<\/strong><\/a>: Del 1 de julio al 23 de agosto y del 2 al 8 de septiembre.<\/li>\n<li><strong>Presencial o telef\u00f3nico<\/strong>: El 4 y 7 de septiembre.<\/li>\n<li><strong>Las personas no abonadas <\/strong>del 14 al 18 de septiembre, tanto presencialmente como telef\u00f3nicamente o mediante correo electr\u00f3nico: deportes.kirolak@zizurnagusia.eus.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>C\u00f3mo inscribir v\u00eda App:<\/strong><\/p>\n<ul>\n<li>Descargar la aplicaci\u00f3n <strong>Kirol Zizur<\/strong> del Play Store o App Store<\/li>\n<li>Iniciar sesi\u00f3n con usuario y contrase\u00f1a<\/li>\n<li>Pulsar en el apartado <strong>[+Nueva reserva]<\/strong><\/li>\n<li>Elegir<strong> inscripciones a cursos<\/strong> y seleccionar el curso en el que est\u00e1s interesado\/a<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-47224\" src=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/04\/Kirola-euskaraz-0-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1280\" srcset=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/04\/Kirola-euskaraz-0-scaled.jpg 2560w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/04\/Kirola-euskaraz-0-300x150.jpg 300w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/04\/Kirola-euskaraz-0-1024x512.jpg 1024w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/04\/Kirola-euskaraz-0-768x384.jpg 768w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/04\/Kirola-euskaraz-0-1536x768.jpg 1536w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/04\/Kirola-euskaraz-0-2048x1024.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> del 01\/07 al 23\/08 y del 02\/09 al 08\/09 (con abono)<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor.<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[219,338],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-47078","class","type-class","status-publish","hentry","wcs-type-baranain-zizur-mayor-orkoien-galar-olza-etxauri-es","wcs-type-comarca-pamplona","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/47078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=47078"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=47078"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=47078"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=47078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}