{"id":48947,"date":"2024-08-28T12:42:19","date_gmt":"2024-08-28T10:42:19","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=48947"},"modified":"2024-09-03T11:34:41","modified_gmt":"2024-09-03T09:34:41","slug":"inscripcion-cursos-de-cultura-en-euskera","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/inscripcion-cursos-de-cultura-en-euskera\/","title":{"rendered":"Inscripci\u00f3n: cursos de Cultura en euskera"},"content":{"rendered":"<p><strong>D\u00edas para inscripci\u00f3n:<\/strong> 04-05-06\/09\/2024<br \/>\n<strong>D\u00f3nde:<\/strong> En el ayuntamiento de Zizur Mayor y <a href=\"https:\/\/deportes.zizurmayor.es:8443\/busact.php\" target=\"_blank\" rel=\"noopener nofollow\">online<\/a><\/p>\n<p>El servicio de cultura de Zizur Mayor oferta a principios de curso actividades y cursos formativos, tanto para p\u00fablico adulto como juvenil e infantil. <a href=\"https:\/\/www.zizurmayorcultura.es\/eu\/news\/informacion-de-cursos-y-actividades-formativas-2024-2025-2\/\" target=\"_blank\" rel=\"noopener nofollow\">En este enlace<\/a> puedes consultar la oferta completa y seguidamente ofrecemos la informaci\u00f3n sobre los cursos en euskera para p\u00fablico infantil y juvenil, \u00a1porque la cultura en euskera es mucho m\u00e1s! Recuerda que la inscripci\u00f3n debe realizarse el 4, 5 o 6 de septiembre en el propio Ayuntamiento u <a href=\"https:\/\/deportes.zizurmayor.es:8443\/busact.php\" target=\"_blank\" rel=\"noopener nofollow\">online en este enlace<\/a>. Las actividades comenzar\u00e1n la primera semana de octubre.<\/p>\n<p><strong>Datos necesarios para la inscripci\u00f3n:<\/strong> Nombres y apellidos, DNI, fecha de nacimiento, n\u00ba de tel\u00e9fono, direcci\u00f3n de correo electr\u00f3nico y n\u00ba de domiciliaci\u00f3n bancaria. La inscripci\u00f3n conlleva el compromiso de pago de la cuota \u00edntegra y esta se podr\u00e1 abonar en un pago \u00fanico o en tres plazos.<\/p>\n<p><strong>FIGURAS Y PERSONAJES CON LEGO (5 a 12 a\u00f1os).<\/strong> Monitorado: Discoverbricks.<br \/>\n<strong>Cu\u00e1ndo:<\/strong> s\u00e1bados, 10:30 &#8211; 12:00 (Octubre a diciembre). Casa de Cultura. <strong>Cuota:<\/strong> 45 euros (materiales incluidos barne). <em>Conoce y construye ciudades, pa\u00edses y civilizaciones, y sella tu pasaporte en cada lugar que visites.<\/em><\/p>\n<p><strong>TALLER DE EXPRESI\u00d3N ART\u00cdSTICA (6 a 9 a\u00f1os).<\/strong> Monitora: Ainhoa Pagola.<br \/>\n<strong>Cu\u00e1ndo:<\/strong> martes, 17:00 &#8211; 18:00 (Octubre a mayo). Casa de Cultura. <strong>Cuota:<\/strong> 75 euros (materiales incluidos). <em>Desarrolla tu creatividad a trav\u00e9s de la pl\u00e1stica.<\/em><\/p>\n<p><strong>GAZTE ANTZERKI-TAILERRA (12 a 16 a\u00f1os):<\/strong><br \/>\n<strong>Cu\u00e1ndo:<\/strong> viernes, 18:30 &#8211; 20:00 (Octubre a marzo). Casa de Cultura. <strong>Cuota:<\/strong> 90 euros. <em>Disfruta compartiendo lecturas, juegos, risas\u2026 El lenguaje del teatro te sorprender\u00e1 y te atrapar\u00e1. Juego, expresividad, lenguajes, movimiento, interpretaci\u00f3n. Vive el teatro.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>D\u00edas para inscripci\u00f3n:<\/strong> 04-05-06\/09\/2024<br \/>\n<strong>D\u00f3nde:<\/strong> En el ayuntamiento de Zizur Mayor y online<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[219,338],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-48947","class","type-class","status-publish","hentry","wcs-type-baranain-zizur-mayor-orkoien-galar-olza-etxauri-es","wcs-type-comarca-pamplona","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/48947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=48947"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=48947"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=48947"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=48947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}