{"id":52743,"date":"2025-02-26T09:44:06","date_gmt":"2025-02-26T08:44:06","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=52743"},"modified":"2025-02-26T10:45:40","modified_gmt":"2025-02-26T09:45:40","slug":"espectaculo-musica-danza-txalaparta-dantzari-ausarta","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/espectaculo-musica-danza-txalaparta-dantzari-ausarta\/","title":{"rendered":"Espect\u00e1culo m\u00fasica, danza, txalaparta: Dantzari ausarta"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 28\/02\/2025, 20:00 h<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor. Casa de Cultura<br \/>\nGrupos: <strong><a href=\"https:\/\/mielotxin.com\/\" target=\"_blank\" rel=\"nofollow noopener\">Mielotxin folk taldea<\/a>, <a href=\"http:\/\/hutsuntxalaparta-eu.blogspot.com\/\" target=\"_blank\" rel=\"nofollow noopener\">Hutsun txalaparta taldea<\/a> eta <a href=\"https:\/\/www.instagram.com\/lauarindantza\/\" target=\"_blank\" rel=\"nofollow noopener\">Lauarin dantza taldea<\/a>.<\/strong><br \/>\n<strong>Entradas:<\/strong> <a href=\"http:\/\/www.zizurmayorcultura.es\/eu\/events\/dantzari-ausarta\/\" target=\"_blank\" rel=\"nofollow noopener\">online<\/a> o en taquilla a 6 euros.<\/p>\n<p>Un espect\u00e1culo con m\u00fasica folk, txalaparta el instrumento tradicional vascos y dantzas&#8230; euskera y cultura vasca, muy apropiado para padres, madres y tambi\u00e9n ni\u00f1os y ni\u00f1as.<\/p>\n<blockquote><p>Ay gran dantzari\u2026 \u00bfQui\u00e9n ser\u00e1 hoy el valiente observador? \u00bfQu\u00e9 es la m\u00fasica sin la danza? Eso s\u00ed que es soledad para los m\u00fasicos. Con estas frases comienza este concierto en el que el grupo de folk Mielotxin quiere hacernos reflexionar. Nuestras plazas siempre han estado llenas de m\u00fasica: el txistu, la gaita, el acorde\u00f3n\u2026 Nos han hecho bailar con aires tradicionales: jota, arin-arin, zortziko, mutildantza o jauzis\u2026<\/p>\n<p>Sin embargo, hoy en d\u00eda, cada vez se baila menos al son de estos instrumentos y mostramos una actitud pasiva parecida a las redes sociales, donde nos convertimos en meros espectadores y observadores. Mielotxin, junto a Hutsun txalaparta y Lauarin, nos presenta \u201cDantzari Ausarta\u2019 y deja en nuestra mano que decidamos qu\u00e9 queremos ser: espectadores o dantzaris.<\/p><\/blockquote>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"DANTZARI AUSARTA\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/EHrCpbDLkWg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 28\/02\/2025, 20:00 h<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor. Casa de Cultura<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,219,338],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-52743","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-baranain-zizur-mayor-orkoien-galar-olza-etxauri-es","wcs-type-comarca-pamplona","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/52743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=52743"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=52743"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=52743"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=52743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}