{"id":58207,"date":"2025-10-30T14:24:09","date_gmt":"2025-10-30T13:24:09","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=58207"},"modified":"2025-10-30T14:24:09","modified_gmt":"2025-10-30T13:24:09","slug":"cuentacuentos-haragi-koloreko-tximeleta-begiradazalea-3","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/cuentacuentos-haragi-koloreko-tximeleta-begiradazalea-3\/","title":{"rendered":"Cuentacuentos: \u201cHaragi koloreko tximeleta begiradazalea\u201d"},"content":{"rendered":"<p><strong>Cu\u00e1ndo<\/strong>: 14\/12\/2025; 17:30<br \/>\n<strong>D\u00f3nde<\/strong>: Eulate. Ludoteca<br \/>\n<a href=\"https:\/\/www.euskarabidea.es\/castellano\/gora-gora-fest\" target=\"_blank\" rel=\"nofollow noopener\">Gora Gora Fest, 2025<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo<\/strong>: 14\/12\/2025; 17:30<br \/>\n<strong>D\u00f3nde<\/strong>: Eulate. Ludoteca<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[233],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-58207","class","type-class","status-publish","hentry","wcs-type-otros-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/58207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=58207"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=58207"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=58207"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=58207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}