{"id":6416,"date":"2018-08-08T12:56:52","date_gmt":"2018-08-08T10:56:52","guid":{"rendered":"http:\/\/eranafarroa.eus\/?post_type=class&#038;p=6416"},"modified":"2018-08-08T14:19:08","modified_gmt":"2018-08-08T12:19:08","slug":"kale-animazioa-txantxariak","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/kale-animazioa-txantxariak\/","title":{"rendered":"Kale animazioa: \u00abTxantxariak\u00bb"},"content":{"rendered":"<p><strong>Fecha<\/strong>: 17\/08\/2018, 19:00<br \/>\n<strong>Lugar<\/strong>: Plaza Francisco Ardanaz \u00abSoldau\u00bb<\/p>\n<p><strong>Organiza<\/strong>: Ayuntamiento de Burlada. Servicio de Euskera<\/p>\n<p>Fiestas de Burlada<\/p>\n<p>Txantxariak son Mari Txipi, Arantxa Zabaleta, Antxon, Txilin eta Txantxibiri Kamino y el burro Braulio, personas\u00a0que viajan por todo el mundo. Por eso conocen muchos juegos divertidos para realizar con todas aquellas personas que se acerquen a pasar la tarde con ellas y ellos. El\u00a0espect\u00e1culo consiste en realizar juegos din\u00e1micos y musicales.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Fecha:<\/strong> 15\/08\/2018, 19:00<br \/>\n<strong>Lugar:<\/strong> Burlada. Plaza Francisco Ardanaz \u00abSoldau\u00bb <\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,224],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-6416","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-burlada-villava-huarte-esteribar-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/6416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=6416"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=6416"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=6416"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=6416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}