{"id":8065,"date":"2018-11-27T08:53:24","date_gmt":"2018-11-27T07:53:24","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=8065"},"modified":"2018-11-27T09:15:59","modified_gmt":"2018-11-27T08:15:59","slug":"epa-txiki-haur-musikala","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/epa-txiki-haur-musikala\/","title":{"rendered":"Musical: \u00abEpa txiki!\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 08\/12\/2018, 18:00<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor. Anfiteatro de la Casa de Cultura<\/p>\n<p><strong>Precio:<\/strong> 4 euros<br \/>\n<strong>Duraci\u00f3n:<\/strong> 50 min<\/p>\n<p><strong>Edad: <\/strong>a partir de 5 a\u00f1os<\/p>\n<p>La compa\u00f1\u00eda Demod\u00e9 Quartet descubri\u00f3 en la larga gira de Epa! Que tambi\u00e9n contaban con muchos y muchas fans j\u00f3venes entre sus incondicionales, as\u00ed que decidi\u00f3 adaptar el espect\u00e1culo para ellos y ellas, realizando nuevas versiones de sus temas favoritos e introduciendo alguna nueva canci\u00f3n. El argumento, sin embargo, no cambia. A lo largo del espect\u00e1culo, los cuatro miembros del grupo ponen todo su empe\u00f1o en demostrar la disparatada teor\u00eda de que todos los estilos musicales, es decir, el rock, el pop, el blues, el reagge \u00a1e incluso el bollywood! tienen su origen en el cancionero euskaldun. \u00a1Toma ya!<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo: <\/strong> 08\/12\/2018, 18:00<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor. Anfiteatro de la Casa de Cultura<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,219],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-8065","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-baranain-zizur-mayor-orkoien-galar-olza-etxauri-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/8065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=8065"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=8065"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=8065"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=8065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}