{"id":8614,"date":"2018-12-20T13:15:28","date_gmt":"2018-12-20T12:15:28","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=8614"},"modified":"2018-12-20T13:27:46","modified_gmt":"2018-12-20T12:27:46","slug":"oliver-magoa-balio-magikoak","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/oliver-magoa-balio-magikoak\/","title":{"rendered":"Oliver Magoa: \u00abBalio magikoak\u00bb"},"content":{"rendered":"<div class=\"col-md-12 col-xs-12 text-left\">\n<p><strong>Cu\u00e1ndo:<\/strong> 02\/01\/2019, 18:00<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor. Casa de Cultura<\/p>\n<p><strong>Edad:<\/strong> a partir de 4 a\u00f1os<strong><br \/>\nPrecio:<\/strong> 4 euros<br \/>\n<strong>Duraci\u00f3n:<\/strong> 80 min.<\/p>\n<div class=\"col-md-12 col-xs-12 text-left\">\n<p>El mago Oliver cree que un escenario es un lugar perfecto desde el que transmitir valores necesarios para el d\u00eda a d\u00eda de la escuela, de la calle o de casa. Y tambi\u00e9n defiende que este objetivo es posible sin perder un \u00e1pice de espectacularidad. Esta obra es la prueba de que tiene raz\u00f3n. Despliega efectos especiales espectaculares, mucho, mucho ritmo y sorprendentes n\u00fameros de magia que atrapan desde el minuto uno. \u00a1No te lo pierdas!<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 02\/01\/2019, 18:00<br \/>\n<strong>D\u00f3nde:<\/strong> Zizur Mayor. Casa de Cultura<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,219],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-8614","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-baranain-zizur-mayor-orkoien-galar-olza-etxauri-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/8614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=8614"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=8614"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=8614"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=8614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}