{"id":9231,"date":"2019-01-28T09:53:23","date_gmt":"2019-01-28T08:53:23","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=9231"},"modified":"2019-02-22T11:58:07","modified_gmt":"2019-02-22T10:58:07","slug":"pirritx-porrotx-eta-marimotots-musua-5","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/pirritx-porrotx-eta-marimotots-musua-5\/","title":{"rendered":"Pirritx, Porrotx eta Marimotots: \u201cMusua\u201d"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 27\/02\/2019, 18:00<br \/>\n<strong>D\u00f3nde:<\/strong> Lumbier. Cine<\/p>\n<p><strong>Organiza:<\/strong> Korrika Kulturala<\/p>\n<p>Mundua mundu denetik, eguzkia biraka ari da eta gu haren inguruan. Eta dei egiten dio lurrari esnatzeko, azaleko zomorroak astindu eta mozorrotzeko. Mundua mundu denetik, hartzak kobazulora sartzen dira neguko solstizioetan eta kilkerrak kanpora atera udakoetan.<\/p>\n<p>Eta guk dantzatu eta kantatu egiten dugu negu zein uda, egin arren euria, atera arren eguzkia, apurtu arren zeruan tximista\u2026 Ihauterietan, San Joanetan, Gabonetan ohitura zaharrak mantendu eta berriak sortzera jolasten dugu. Munduak biraka segi dezan. Eguzkiak ez ezik, musuek ere biraka jartzen dutelako mundua. Eta musuek biraka jartzen gaituztelako gu.<\/p>\n<p>Eta zu? \u201d<\/p>\n<p><strong>Leire Bilbao<\/strong><\/p>\n<p><em>\u201cDesde que el mundo es mundo, el sol gira y alrededor de \u00e9l giramos las personas. Y el sol despierta la tierra y as\u00ed, los bichitos se disfrazan y bailan. Desde que el mundo es mundo, en los solsticios de invierno las familias de osos entran en las cuevas y salen los grillos en los de verano.<\/em><\/p>\n<p><em>Cantamos y bailamos tanto en invierno como en verano, haga sol, llueva o revienten rel\u00e1mpagos en el cielo\u2026 Jugamos con las viejas y creamos nuevas costumbres en Carnavales, San Juanes, Navidad\u2026para que el mundo siga girando. Pero no es el sol el \u00fanico que hace girar al mundo; los besos, tambi\u00e9n hacen girar al mundo y a las personas.<\/em><\/p>\n<p><em>A ti tambi\u00e9n, \u00bfa que s\u00ed?\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"MUSUA bideoklipa\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/L96tSJ1OngQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo: <\/strong>27\/02\/2019, 18:00<br \/>\n<strong>D\u00f3nde: <\/strong>Lumbier<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,233],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-9231","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-otros-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/9231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=9231"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=9231"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=9231"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=9231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}