{"id":9264,"date":"2019-01-28T14:07:39","date_gmt":"2019-01-28T13:07:39","guid":{"rendered":"https:\/\/eranafarroa.eus\/?post_type=class&#038;p=9264"},"modified":"2019-01-28T14:07:39","modified_gmt":"2019-01-28T13:07:39","slug":"teatro-familiar-in-concert","status":"publish","type":"class","link":"https:\/\/eranafarroa.eus\/es\/eranafarroa\/teatro-familiar-in-concert\/","title":{"rendered":"Teatro familiar: \u00abIn concert\u00bb"},"content":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 03\/03\/2019, 18:30-19:25<br \/>\n<strong>D\u00f3nde:<\/strong> Mutilva. Auditorio de la Casa de Cultura del Valle de Aranguren (Pl. Eguzki s\/n, 31192)<\/p>\n<p><strong>Edad:<\/strong> a partir de 3 a\u00f1os<br \/>\n<strong>Precio:<\/strong> 3 euros<\/p>\n<p><strong>Organiza:<\/strong> \u00c1rea de Cultura<br \/>\nTel. 948291489<br \/>\n<a href=\"mailto:c.culturarecepcion@gmail.com\">c.culturarecepcion@gmail.com<\/a><\/p>\n<p><strong>Compa\u00f1\u00eda:<\/strong> Trokolo Teatro<\/p>\n<p><strong>Para comprar entradas<\/strong>:<\/p>\n<ul>\n<li>De antemano: la misma semana de la actividad, de lunes a viernes, de 11:00 a 13:00 y de 17:00 a 21:00, en la recepci\u00f3n de la Casa de Cultura.<\/li>\n<li>El d\u00eda de la sesi\u00f3n, si quedan entradas, media hora de la funci\u00f3n.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Cu\u00e1ndo:<\/strong> 03\/03\/2019, 18:30-19:25<br \/>\n<strong>D\u00f3nde:<\/strong> Mutilva. Casa de Cultura del Valle de Aranguren<\/p>\n","protected":false},"template":"","meta":[],"wcs-type":[228,225],"wcs-room":[],"wcs-instructor":[214],"class_list":["post-9264","class","type-class","status-publish","hentry","wcs-type-agenda-destacada-es","wcs-type-valle-de-egues-aranguren-es","wcs-instructor-era"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class\/9264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=9264"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-type?post=9264"},{"taxonomy":"wcs-room","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-room?post=9264"},{"taxonomy":"wcs-instructor","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/wcs-instructor?post=9264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}