{"id":17122,"date":"2020-02-25T07:30:47","date_gmt":"2020-02-25T06:30:47","guid":{"rendered":"https:\/\/eranafarroa.eus\/?p=17122"},"modified":"2020-02-24T14:18:06","modified_gmt":"2020-02-24T13:18:06","slug":"filmin-en-euskera-una-nueva-opcion","status":"publish","type":"post","link":"https:\/\/eranafarroa.eus\/es\/filmin-en-euskera-una-nueva-opcion\/","title":{"rendered":"Filmin en euskera, una nueva opci\u00f3n"},"content":{"rendered":"<p>\u00a1La de veces que se teclea!: \u201cPel\u00edculas en euskera para ni\u00f1as\/os\u201d. Porque disfrutar en la butaca del cine de un estreno tiene un encanto especial, pero siendo sinceros, hace tiempo que no es necesario salir de casa para ver una peli. Y en esas tardes lluviosas, con un bol de palomitas en el sof\u00e1\u2026<\/p>\n<p>Filmin.es, por ejemplo, es una plataforma que permite ver pel\u00edculas online. Nace en 2008 y desde entonces ha acumulado m\u00e1s de 10.000 t\u00edtulos en su cat\u00e1logo, organizado en canales tem\u00e1ticos, colecciones, secci\u00f3n infantil\u2026 Estos d\u00edas ha sido noticia porque ha estrenado un nuevo canal tem\u00e1tico: <a href=\"https:\/\/www.filmin.es\/canal\/filmin-euskaraz\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Filmin Euskaraz<\/a>.<\/p>\n<p>Por lo tanto, ya est\u00e1 aqu\u00ed el primer canal de streaming en euskera. Lo primero que hay que hacer es registrarse, ya sea con un correo electr\u00f3nico o con una cuenta de Facebook. Luego ya se puede decidir si se hace o no una subscripci\u00f3n. Obviamente, para aquellas familias muy aficionadas a la pantalla es una buena opci\u00f3n, porque sale mejor de precio. Pero, tambi\u00e9n existe la opci\u00f3n de alquilar pelis sin tener que subscribirse.<\/p>\n<p>Toda la informaci\u00f3n necesaria est\u00e1 <a href=\"https:\/\/www.filmin.es\/suscribete\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">aqu\u00ed<\/a>, pero se puede resumir en tres opciones:<\/p>\n<ul>\n<li><strong>Sin subscripci\u00f3n<\/strong>: la mejor opci\u00f3n para ver pel\u00edculas sueltas, sin ning\u00fan compromiso. El precio oscila entre 2 y 4 \u20ac por peli y tienes 72 horas para verla.<\/li>\n<li><strong>Vales sin subscripci\u00f3n<\/strong>: los hay de 5 y de 20 pel\u00edculas y no caducan.<\/li>\n<li><strong>Planes de subscripci\u00f3n<\/strong>: B\u00e1sico y Plus. Existe la opci\u00f3n mensual (8-15 \u20ac\/mes) y la anual (7-10 \u20ac\/mes), y adem\u00e1s de pel\u00edculas, tambi\u00e9n puedes ver series.<\/li>\n<\/ul>\n<p>Ya hay unos 40 t\u00edtulos en euskera, de los cuales 14 est\u00e1n clasificados para el p\u00fablico infantil. La mayor\u00eda son estrenos posteriores al 2015, y en general, han recibido muy buena cr\u00edtica. Adem\u00e1s, hay una amplia variedad: desde <em>Nur y el templo del drag\u00f3n<\/em>, basada en el libro de Toti Mart\u00ednez de Lezea, hasta <em>La alfombra m\u00e1gica<\/em>, un remake de las 1001 noches.<\/p>\n<p>De todos modos, lo mejor ser\u00e1 que cada cual elija seg\u00fan sus preferencias y gustos, y que de vez en cuando entre en la plataforma, porque los creadores ya han adelantado su intenci\u00f3n de ampliar el cat\u00e1logo de euskera, al igual que hicieron con las pel\u00edculas en catal\u00e1n en Filmin Cat.<\/p>\n<p><span style=\"font-size: 12px; color: #808080;\"><em>\u00a9 ERA<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1La de veces que se teclea!: \u201cPel\u00edculas en euskera para ni\u00f1as\/os\u201d. Porque disfrutar en la butaca del cine de un estreno tiene un encanto especial, pero siendo sinceros, hace tiempo que no es necesario salir de casa para ver una peli. Y en esas tardes lluviosas, con un bol de palomitas en el sof\u00e1\u2026 Filmin.es, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-17122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/17122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/comments?post=17122"}],"version-history":[{"count":0,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/17122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media\/17119"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=17122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/categories?post=17122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/tags?post=17122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}