{"id":23062,"date":"2021-03-11T12:09:36","date_gmt":"2021-03-11T11:09:36","guid":{"rendered":"https:\/\/eranafarroa.eus\/?p=23062"},"modified":"2023-02-14T15:08:28","modified_gmt":"2023-02-14T14:08:28","slug":"propuestas-para-familias-que-viven-en-pueblos-euskaldunes","status":"publish","type":"post","link":"https:\/\/eranafarroa.eus\/es\/propuestas-para-familias-que-viven-en-pueblos-euskaldunes\/","title":{"rendered":"Propuestas para familias que viven en pueblos euskaldunes"},"content":{"rendered":"<p><em><span style=\"font-weight: 400;\">En euskera!! \u2026 \u00bfC\u00f3mo si no?<\/span><\/em><span style=\"font-weight: 400;\"> responden los ni\u00f1os de Goizueta, Zubieta, Arantza o Aniz, al\u00a0 preguntarles\u00a0 c\u00f3mo se relacionan entre ellos. Y es que, en la mayor\u00eda de comarcas del noroeste de Navarra el euskera goza de una buena salud: pr\u00e1cticamente toda la poblaci\u00f3n sabe y habla euskera. Gracias al esfuerzo realizado por miles de familias, el idioma se ha transmitido de generaci\u00f3n en generaci\u00f3n de manera ininterrumpida, una de las claves m\u00e1s importantes para mantener vivo un idioma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero, no todo est\u00e1 ganado, ni siquiera aqu\u00ed. Siendo \u00e9sta una zona donde el euskera est\u00e1 presente en el d\u00eda a d\u00eda, su situaci\u00f3n a\u00fan es vulnerable.\u00a0 Hay que tener en cuenta que est\u00e1 en proceso de recuperaci\u00f3n y que no tiene el tratamiento prioritario y la presencia masiva que tiene el castellano. Se ve claramente en la producci\u00f3n audiovisual y en la creaci\u00f3n de contenidos digitales dirigidos al p\u00fablico infantil, por poner un ejemplo. Son grandes fuentes de entretenimiento a las que ni\u00f1as y ni\u00f1os dedican mucho tiempo. Y s\u00ed, el euskera avanza,\u00a0 pero ocupa un lugar menor. Por eso, es importante que la familia demuestre una actitud positiva y activa hacia el uso y presencia del euskera, sepa o no euskera. Para ello se pueden tener en cuenta las siguientes propuestas:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Actividades extraescolares<\/strong><span style=\"font-weight: 400;\"><strong>:<\/strong> En estas comarcas la mayor\u00eda de las extraescolares son en euskera. Participar en ellas es muy beneficioso porque, de esa manera, el euskera pasa a ser tambi\u00e9n el idioma de los espacios de ocio, de disfrute, no s\u00f3lo de la escuela; y al mismo tiempo, es la lengua de las relaciones informales entre ni\u00f1as y ni\u00f1os.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Cultura en euskera:<\/strong><span style=\"font-weight: 400;\"> La m\u00fasica, el cine, la literatura, el teatro\u2026 todas son buenas opciones para el desarrollo individual, social y ling\u00fc\u00edstico en la infancia. Mediante esas disciplinas culturales se potencian la imaginaci\u00f3n, la creatividad, la capacidad de comunicaci\u00f3n y, de igual manera, influyen en el\u00a0 apego hacia el euskera. En la secci\u00f3n de<\/span><a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400;\">Recursos<\/span><\/a><span style=\"font-weight: 400;\"> de ERA hay una buena colecci\u00f3n de propuestas culturales, y en la <\/span><a href=\"https:\/\/eranafarroa.eus\/es\/agenda\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Agenda<\/span><\/a><span style=\"font-weight: 400;\"> se pueden consultar las actividades en euskera organizadas en estas comarcas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Internet y aplicaciones en euskera<\/strong><span style=\"font-weight: 400;\"><strong>:<\/strong> Las ni\u00f1as y ni\u00f1os las utilizan a diario, y el euskera se ha ido abriendo paso en ese mundo. Cada vez est\u00e1 presente en m\u00e1s opciones, ya sea en Internet o en las<\/span><a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/app-s-y-juguetes\/\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400;\">aplicaciones<\/span><\/a><span style=\"font-weight: 400;\">. Y tenerlas configuradas o instaladas en euskera no es ninguna tonter\u00eda. Por ejemplo, tener el<\/span><a href=\"https:\/\/eranafarroa.eus\/es\/el-inicio-de-curso-todo-a-punto-y-bien-configurado\/\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400;\">navegador en euskera<\/span><\/a><span style=\"font-weight: 400;\"> puede ayudar mucho a la hora de hacer la tarea. Al realizar una b\u00fasqueda en euskera, el navegador prioriza los resultados encontrados en ese idioma.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Elige medios de comunicaci\u00f3n en euskera:<\/strong><span style=\"font-weight: 400;\"> Se dice que los medios de comunicaci\u00f3n son una ventana al mundo. En estos pueblos del noroeste de Navarra hay varios medios de comunicaci\u00f3n locales en euskera que pueden ayudar mucho a la hora de fortalecer el nivel del euskera de ni\u00f1as y ni\u00f1os. Escuchar la radio en euskera, sin ir m\u00e1s lejos, puede ayudar a familiarizarse o afianzar aspectos como la pronunciaci\u00f3n o la entonaci\u00f3n. Leer la secci\u00f3n de los cumplea\u00f1os de la revista Ttipi-ttapa, por ejemplo, puede ayudarles en el h\u00e1bito de la lectura.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Costumbres y riqueza cultural, tanto de\u00a0 generaciones anteriores como de las actuales:<\/strong><span style=\"font-weight: 400;\"> m\u00e1s all\u00e1 de una idea bonita, dar a conocer a las ni\u00f1as y ni\u00f1os las costumbres y la riqueza cultural de las generaciones anteriores es una manera de fortalecer el v\u00ednculo hacia la cultura local. Pero tambi\u00e9n es importante que conozcan las expresiones culturales contempor\u00e1neas, prestando especial atenci\u00f3n a las creadas en euskera.<\/span><\/li>\n<\/ul>\n<p>\u00a9 ERA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En euskera!! \u2026 \u00bfC\u00f3mo si no? responden los ni\u00f1os de Goizueta, Zubieta, Arantza o Aniz, al\u00a0 preguntarles\u00a0 c\u00f3mo se relacionan entre ellos. Y es que, en la mayor\u00eda de comarcas del noroeste de Navarra el euskera goza de una buena salud: pr\u00e1cticamente toda la poblaci\u00f3n sabe y habla euskera. Gracias al esfuerzo realizado por miles [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":23115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-23062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recursos"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/23062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/comments?post=23062"}],"version-history":[{"count":0,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/23062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media\/23115"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=23062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/categories?post=23062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/tags?post=23062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}