{"id":2423,"date":"2018-01-11T09:23:58","date_gmt":"2018-01-11T08:23:58","guid":{"rendered":"http:\/\/eranafarroa.eus\/?p=2423"},"modified":"2024-04-09T12:33:37","modified_gmt":"2024-04-09T10:33:37","slug":"canciones-para-dormir-tranquilidad-y-dulzura-en-el-regazo","status":"publish","type":"post","link":"https:\/\/eranafarroa.eus\/es\/canciones-para-dormir-tranquilidad-y-dulzura-en-el-regazo\/","title":{"rendered":"Canciones para dormir: tranquilidad y dulzura en el regazo"},"content":{"rendered":"<p>Las nanas son canciones populares destinadas a calmar, relajar y dormir a los beb\u00e9s. Existen en todas las culturas, con el mismo fin. \u00a0Son universales.<\/p>\n<p>Normalmente, las cantan las madres o padres, y mediante ellas se transmite seguridad, protecci\u00f3n \u00a0y cercan\u00eda a los beb\u00e9s. No hace falta tener buena voz para cantarlas, ya que los beb\u00e9s valoran m\u00e1s la protecci\u00f3n y el afecto que reciben en ese momento que la calidad de la interpretaci\u00f3n. Por ese motivo, la clave reside en que quien canta sea una persona cercana. El efecto tranquilizador se debe a que el beb\u00e9, desde el quinto mes del embarazo, ya escucha la voz de su madre y las de las personas que le rodean, y empieza a familiarizarse con ellas. Por eso, al escuchar la nana, se calma y se duerme.<\/p>\n<p>Las canciones de cuna se han transmitido de generaci\u00f3n en generaci\u00f3n, de manera oral, tambi\u00e9n en euskera. \u00a0Como la mayor\u00eda no se han escrito o grabado, muchas han ido cambiando y otras, lamentablemente, no han llegado hasta nuestros d\u00edas.<\/p>\n<p>No obstante, en <a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/musica\/\" target=\"_blank\" rel=\"noopener noreferrer\">esta secci\u00f3n<\/a> de ERA.EUS encontrar\u00e1s una \u00a0colecci\u00f3n muy interesante, pero este art\u00edculo quiere hacer especial menci\u00f3n de dos canciones de cuna <strong>grabadas <\/strong>por el estadounidense <a href=\"https:\/\/es.wikipedia.org\/wiki\/Alan_Lomax\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Alan Lomax<\/a> en 1952 y 1953 <strong>en Navarra<\/strong>, concretamente en Erratzu y \u00a0Uitzi. Las dos tienen el mismo t\u00edtulo, <em>Haurra egizu lo<\/em> (Du\u00e9rmete ni\u00f1o\/ni\u00f1a), pero son dos versiones distintas (las dos canciones se pueden escuchar <a href=\"https:\/\/es.wikipedia.org\/wiki\/The_Spanish_Recordings:_Basque_Country:_Navarre\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">en este disco<\/a>):<\/p>\n<ul>\n<li>En febrero de 1953, en <strong>Erratzu, <\/strong>Lomax grab\u00f3 a <a href=\"https:\/\/archive.culturalequity.org\/field-work\/spain-1952-1953\/erratzu-153\/haurra-egizu-lo\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Mar\u00eda Fagoaga<\/a>.<\/li>\n<li>En diciembre de 1952, en <strong>Uitzi, <\/strong>Lomax grab\u00f3 a <a href=\"https:\/\/archive.culturalequity.org\/field-work\/spain-1952-1953\/uitzi-1252\/haurra-egizu-lo\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Juanita Aspiroz<\/a>.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las nanas son canciones populares destinadas a calmar, relajar y dormir a los beb\u00e9s. Existen en todas las culturas, con el mismo fin. \u00a0Son universales. Normalmente, las cantan las madres o padres, y mediante ellas se transmite seguridad, protecci\u00f3n \u00a0y cercan\u00eda a los beb\u00e9s. No hace falta tener buena voz para cantarlas, ya que los [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2421,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42,55],"tags":[125,140,148,168,127],"class_list":["post-2423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa","category-recursos","tag-aprendiendo","tag-cultura","tag-musica","tag-nosabes-es","tag-sisabes"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/2423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/comments?post=2423"}],"version-history":[{"count":0,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/2423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media\/2421"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=2423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/categories?post=2423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/tags?post=2423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}