{"id":42842,"date":"2023-09-21T08:00:15","date_gmt":"2023-09-21T06:00:15","guid":{"rendered":"https:\/\/eranafarroa.eus\/?p=42842"},"modified":"2024-05-20T10:47:51","modified_gmt":"2024-05-20T08:47:51","slug":"comienza-el-curso-10-meses-10-causas","status":"publish","type":"post","link":"https:\/\/eranafarroa.eus\/es\/comienza-el-curso-10-meses-10-causas\/","title":{"rendered":"Comienza el curso: 10 meses, 10 causas"},"content":{"rendered":"<p>Acaba de empezar el curso y tenemos todo un mundo por delante, la agenda echa humo, intentamos cuadrar el calendario semanal y tambi\u00e9n prever lo que traer\u00e1 el a\u00f1o escolar. Aqu\u00ed, condensado, y con la perspectiva de todo el curso 2023-2024, una propuesta para cada mes:<\/p>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Septiembre, tiempo de inscripciones: extraescolares y agenda cultural<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>Coincidiendo con el comienzo del curso, las familias se organizan la semana, las tardes\u2026 tratando de compaginar horarios y calendarios: Zumba, <a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/educacion\/escuelas-de-musica-navarras\/\" target=\"_blank\" rel=\"noopener\">escuela de m\u00fasica<\/a>, pintura, ajedrez, Lego, balonmano,&#8230; y tambi\u00e9n en esto conviene mirar a la oferta a trav\u00e9s de las gafas del euskera. Practicar aficiones, y encima hacerlo en euskera, y con amigas y amigos \u00a1es una oportunidad que no pod\u00e9is dejar pasar!<\/p>\n<p>Adem\u00e1s, habr\u00e1 obras de teatro, talleres, cuentacuentos, cine\u2026 en euskera casi todas las semanas a lo largo de Navarra: echa un vistazo a la <a href=\"https:\/\/eranafarroa.eus\/es\/agenda\/\" target=\"_blank\" rel=\"noopener\">agenda Navarra<\/a> o la de <a href=\"https:\/\/eranafarroa.eus\/es\/agenda-comarcal\/\" target=\"_blank\" rel=\"noopener\">tu comarca<\/a>.<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Octubre: ejemplaridad, valores, motivaci\u00f3n y oportunidades<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>Cuando vamos a cruzar una calle o a la hora de seleccionar el cubo de basura correcto, actuamos conscientemente y con responsabilidad, m\u00e1s a\u00fan cuando estamos con nuestras hijas e hijos. Sobra decir que nos esforzamos en ser ejemplares. Con los idiomas, a veces, pasa algo similar. Las ni\u00f1as y ni\u00f1os perciben la manera en la que reaccionamos ante una conversaci\u00f3n en euskera que no entendemos o que no seguimos del todo, pero tambi\u00e9n son muy conscientes\u00a0cuando mostramos inter\u00e9s por que ellas y ellos lo aprendan. Es un goteo constante que\u00a0va moldeando tambi\u00e9n el lugar que ocupa este idioma en su mundo. Todo suma y puede contribuir a que nuestros hijos e hijas lo utilicen m\u00e1s.<\/p>\n<p>Por ello, del 19 al 29 de octubre se llevar\u00e1 a cabo la campa\u00f1a <em>Haurren aurrean helduok heldu<\/em>, donde se busca que padres y madres que saben euskera lo utilicen m\u00e1s a\u00fan, tambi\u00e9n entre personas adultas. Y si no sabemos euskera, tambi\u00e9n podemos contribuir facilitando el uso del euskera explicitando nuestra actitud favorable y <a href=\"https:\/\/youtu.be\/oaHj8C-8FMQ\" target=\"_blank\" rel=\"noopener nofollow\">ofreciendo valores positivos, motivaci\u00f3n y oportunidades<\/a>.<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Noviembre, formaci\u00f3n tambi\u00e9n para padres y madres: ERA Eskolak<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>Durante la crianza hay momentos clave, o fases, en las que es conveniente reflexionar sobre cu\u00e1l ser\u00e1 el lugar del euskera. Por ejemplo, el momento del nacimiento, al empezar la escuela, al pasar al segundo ciclo, al empezar con las extraescolares&#8230; En la secci\u00f3n <a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/consejos-para-madres-padres\/\" target=\"_blank\" rel=\"noopener\">Consejos para padres y madres<\/a> tienes algunas pistas.<\/p>\n<p>As\u00ed mismo, en el mismo apartado encontrar\u00e1s ERA Eskolak. En ella hemos invitado a expertas y expertos a exponer temas tales como \u00abLibros y recursos para animar a la lectura en euskera\u00bb o\u00a0 \u00abFamilia: beneficios y modos de acompa\u00f1ar a las ni\u00f1as y ni\u00f1os en su aprendizaje del euskera\u00bb, claves fundamentales distribuidas en c\u00f3modos videos de unos 10 minutos. Adem\u00e1s, en noviembre estrenamos una nueva edici\u00f3n de ERA Eskolak con tres nuevos temas y ponentes.<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Diciembre, \u00bfy los regalos? Cat\u00e1logo de productos en euskera<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>Casi sin darnos cuenta van a llegar las vacaciones de invierno, y es posible que las familias aprovechen esta \u00e9poca para hacer regalos; bien sea por un cumplea\u00f1os, por Olentzero, o por <em>San Queremos<\/em>, conviene aprovechar la oportunidad para regalar euskera. \u00bfC\u00f3mo? El Cat\u00e1logo de Productos en Euskera realiza anualmente una selecci\u00f3n de los productos existentes en el mercado, teniendo en cuenta la novedad, idoneidad y calidad: <a href=\"http:\/\/www.katalogoa.eus\" target=\"_blank\" rel=\"noopener nofollow\">www.katalogoa.eus<\/a>.<\/p>\n<p>As\u00ed mismo, ERA ha hecho una <a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/app-s-y-juguetes\/\" target=\"_blank\" rel=\"noopener\">selecci\u00f3n de juegos de mesa<\/a> en colaboraci\u00f3n con Dindaia, y Galtzagorri dispone una gran <a href=\"https:\/\/www.ibbygaltzagorri.eus\/es\/literatura-infantil-y-joven-en-euskara\/imprescindibles\" target=\"_blank\" rel=\"noopener nofollow\">lista de lecturas imprescindibles<\/a>; dos herramientas estupendas para ayudaros a elegir regalo.<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Enero, \u00bfte atreves a jugar en euskera sin saber el idioma?<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>Jugar con nuestras hijas e hijos, dedicar un tiempo a la diversi\u00f3n, es m\u00e1s serio de lo que se tiende a pensar: sirve para fortalecer los lazos afectivos, facilita la comunicaci\u00f3n y la creaci\u00f3n de relaciones basadas en la confianza e incrementa su deseo de participar en actividades conjuntas y de querer compartir tiempo. Y si lo hacemos en euskera, mejor que mejor; pero, \u00bfes posible?<\/p>\n<p><a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/juego\/jolasak-eta-solasak\/\" target=\"_blank\" rel=\"noopener\"><i>Jolasak eta Solasak<\/i><\/a> es una colecci\u00f3n de v\u00eddeos donde aprenderemos a saltar a la comba, juegos de manos o f\u00f3rmulas de echar a suertes. Tambi\u00e9n tienes las letras en formato PDF y los videos cuentan con subt\u00edtulos en castellano. Elige una letra f\u00e1cil de aprender, que le pueda gustar a tu hija o hijo, y \u00a1ponlo en pr\u00e1ctica en el parque o patio de la escuela!<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Febrero, la prematr\u00edcula escolar: compartir la experiencia<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>Cuando llega la hora de la prematr\u00edcula es posible que surjan dudas, tales como la elecci\u00f3n del centro o, en algunos casos, tambi\u00e9n el modelo ling\u00fc\u00edstico; lo habitual es recurrir a las jornadas de puertas abiertas, al profesorado, pero tambi\u00e9n es natural solicitar la experiencia personal de conocidos y conocidas que ya tienen a sus hijos e hijas en el modelo en euskera. As\u00ed mismo, en ERA hemos recopilado las <a href=\"https:\/\/eranafarroa.eus\/es\/modelo-d-preguntas-mas-frecuentes\/\" target=\"_blank\" rel=\"noopener\">Preguntas m\u00e1s frecuentes de padres y madres<\/a> en varios idiomas.<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Marzo, corriendo, corriendo... \u00a1llega Korrika!<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>2024 huele <a href=\"https:\/\/es.wikipedia.org\/wiki\/Korrika\" target=\"_blank\" rel=\"noopener nofollow\">a Korrika<\/a>. Pero es que\u00a0 adem\u00e1s de ser una carrera multitudinaria en favor del euskera, es ese momento en el que el calendario se llena de actividades culturales y\u00a0 fiestas. Tambi\u00e9n sirve para plantearse aprender euskera, ya sea como proyecto familiar o personal. De cualquier manera, requiere de tiempo y esfuerzo, pero a su vez resulta muy satisfactorio.<\/p>\n<p>As\u00ed mismo, participar en la Korrika y las actividades previas a la misma, sean fiestas, o actuaciones culturales, ayudan a tejer comunidad y fortalecer los lazos entre personas euskaldunes y otras familias que aprenden euskera. Korrika es una iniciativa emocionante que no tiene edad y se puede disfrutar en familia; esos lazos, conocer a otra gente con la que compartir esa alegr\u00eda y generar recuerdos que nos acompa\u00f1ar\u00e1n toda la vida, ser\u00e1n abono para un mayor apego y uso del euskera.<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Abril, inscripci\u00f3n en campamentos de verano: alegr\u00edas, juventud...<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>\u00bfSab\u00edas que Edurne Azkarate, actriz de la pel\u00edcula Irati, tambi\u00e9n particip\u00f3 en los campamentos de verano en euskera? <a href=\"https:\/\/youtu.be\/XhmljNJ3F6w?si=94AuZ9n-T8K72AQG\" target=\"_blank\" rel=\"noopener nofollow\">Guarda excelentes recuerdos<\/a> y hace especial hincapi\u00e9 en lo importante que fueron para ella. Anualmente, hacia marzo-abril, en ERA se publica la <a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/oferta-extraescolar\/campamentos\/\" target=\"_blank\" rel=\"noopener\">informaci\u00f3n de los campamentos<\/a> de verano en euskera.<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Mayo, naturaleza y euskera: planes y paseos<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>El cuento es arte y mucho m\u00e1s. Sirve para estrechar lazos afectivos y, c\u00f3mo no, tambi\u00e9n para disfrutar. \u00a1Y qu\u00e9 decir de los paseos y planes en familia! As\u00ed, en ERA.eus puedes disfrutar de <a href=\"https:\/\/eranafarroa.eus\/es\/recursos\/cuentos\/videocuentos-y-excursiones\/\" target=\"_blank\" rel=\"noopener\">paseo-cuentos<\/a> y encontrar propuestas para visitar rincones muy especiales: <a href=\"https:\/\/eranafarroa.eus\/es\/planes-de-primavera-iii-galeones-y-ballenas\/\" target=\"_blank\" rel=\"noopener\">galeones y ballenas<\/a>, <a href=\"https:\/\/eranafarroa.eus\/es\/planes-de-primavera-paseos-por-el-monte\/\" target=\"_blank\" rel=\"noopener\">visitar Peru-harri<\/a>, un <a href=\"https:\/\/eranafarroa.eus\/es\/los-gemelos-de-lorka-y-la-lamia-de-iturketa-audio-cuento\/\" target=\"_blank\" rel=\"noopener\">centro de interpretaci\u00f3n sobre apicultura<\/a>\u2026<br \/>\n<\/div><\/div>\n<p><strong><div class=\"symple-toggle state-closed \"><h3 class=\"symple-toggle-trigger \">Junio, \u00a1ya llega el verano!, de la mochila del colegio a la maleta<\/h3><div class=\"symple-toggle-container symple-clearfix\"><\/strong>Incluso cuando estamos de lectura en la tumbona, tambi\u00e9n podemos fomentar el euskera, ya que <a href=\"https:\/\/eranafarroa.eus\/es\/los-pequenos-gestos-tambien-cuentan-en-verano-2\/\" target=\"_blank\" rel=\"noopener\">los peque\u00f1os gestos tambi\u00e9n cuentan<\/a>; o, si te vas de vacaciones, te ofrecemos las <a href=\"https:\/\/eranafarroa.eus\/es\/te-vas-de-vacaciones-como-sobrevivir-al-viaje-en-coche-tren\/\" target=\"_blank\" rel=\"noopener\">claves para sobrevivir al viaje familiar en coche o tren<\/a>, \u00a1o para hacer <a href=\"https:\/\/eranafarroa.eus\/es\/la-importancia-del-contacto-con-el-euskera-tambien-en-verano\/\" target=\"_blank\" rel=\"noopener\">mil cosas m\u00e1s<\/a>! Utiliza la desconexi\u00f3n de la rutina para buscar conexiones inhabituales con el euskera.<br \/>\n<\/div><\/div>\n<p><em>\u00a9 ERA<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acaba de empezar el curso y tenemos todo un mundo por delante, la agenda echa humo, intentamos cuadrar el calendario semanal y tambi\u00e9n prever lo que traer\u00e1 el a\u00f1o escolar. Aqu\u00ed, condensado, y con la perspectiva de todo el curso 2023-2024, una propuesta para cada mes: \u00a9 ERA<\/p>\n","protected":false},"author":4,"featured_media":42838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,55],"tags":[],"class_list":["post-42842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al-salir","category-recursos"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/42842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/comments?post=42842"}],"version-history":[{"count":0,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/42842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media\/42838"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=42842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/categories?post=42842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/tags?post=42842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}