{"id":46567,"date":"2024-03-14T14:24:26","date_gmt":"2024-03-14T13:24:26","guid":{"rendered":"https:\/\/eranafarroa.eus\/?p=46567"},"modified":"2024-03-14T14:54:51","modified_gmt":"2024-03-14T13:54:51","slug":"korrika-la-carrera-donde-todos-quieren-participar","status":"publish","type":"post","link":"https:\/\/eranafarroa.eus\/es\/korrika-la-carrera-donde-todos-quieren-participar\/","title":{"rendered":"Korrika, la carrera donde todos quieren participar"},"content":{"rendered":"<h4><strong>Ni\u00f1as, ni\u00f1os, j\u00f3venes, hijos, hijas, madres, padres, abuelas, abuelos, conocidos, desconocidas, amigas, vecinas\u2026 en la KORRIKA hay sitio para todos. Entre todos aupar\u00e1n la carrera kil\u00f3metro a kil\u00f3metro hasta llegar a Baiona.<\/strong><\/h4>\n<p>Como es bien sabido, la Korrika es una iniciativa multitudinaria a favor del euskera, plena de emoci\u00f3n y completamente participativa. Desde que se realiz\u00f3 por\u00a0 <a href=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/03\/Logoa1.jpeg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-46580\" src=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/03\/Logoa1.jpeg\" alt=\"logo Korrika\" width=\"316\" height=\"206\" srcset=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/03\/Logoa1.jpeg 1080w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/03\/Logoa1-300x195.jpeg 300w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/03\/Logoa1-1024x666.jpeg 1024w, https:\/\/eranafarroa.eus\/wp-content\/uploads\/2024\/03\/Logoa1-768x499.jpeg 768w\" sizes=\"auto, (max-width: 316px) 100vw, 316px\" \/><\/a>primera vez en 1980 ha conseguido poner en marcha a miles de personas de todas las edades, adem\u00e1s durante estos 43 a\u00f1os la participaci\u00f3n ha ido en aumento y siempre se ha destacado el car\u00e1cter plural de la carrera, ya que hay lugar para todas y todos: ni\u00f1os y mayores, alumnos de euskaltegis, ex-alumnos, gente que ha aprendido euskera en la escuela, familias que han ido transmitiendo la lengua de generaci\u00f3n en generaci\u00f3n\u2026<\/p>\n<p>Es una gran carrera colectiva a favor del euskera y tiene dos objetivos fundamentales: impulsar la concienciaci\u00f3n a favor del euskera y recaudar fondos para los euskaltegis de AEK. Al fin y al cabo, para que una lengua se mantenga saludable es esencial que tenga un buen n\u00famero de hablantes.<\/p>\n<p><a href=\"https:\/\/www.korrika.eus\/es\/\" target=\"_blank\" rel=\"noopener nofollow\">La edici\u00f3n del 2024<\/a> dar\u00e1 comienzo hoy mismo, 14 de marzo, en Irun, y finalizar\u00e1 el d\u00eda 24 en Baiona. El testigo portador del mensaje de este a\u00f1o recorrer\u00e1 alrededor de 2.500 kil\u00f3metros de mano en mano. A lo largo de esos d\u00edas las familias tendr\u00e1n la opci\u00f3n de participar en esta carrera por el euskera, padres y madres junto con hijas e hijos, acompa\u00f1ando al testigo en su recorrido.<\/p>\n<p>EL recorrido de la Korrika recorre buena parte de nuestro territorio, son muchos los kil\u00f3metros que cubre, y de tal modo cada cual puede elegir el d\u00eda, hora y tramo que m\u00e1s le conviene. El recorrido completo, junto con calendario y horarios, <a href=\"https:\/\/www.korrika.eus\/es\/recorrido\" target=\"_blank\" rel=\"noopener nofollow\">se puede consultar en la p\u00e1gina web de la Korrika 23.<\/a><\/p>\n<p>HARRO HERRI es el lema de la edici\u00f3n de este a\u00f1o 2024. Un pueblo orgulloso por la riqueza de su idioma, de su cultura, de su gente y sus tradiciones. Cada cual desde su posici\u00f3n y situaci\u00f3n, siempre tiene opci\u00f3n de abrirle el camino y de darle apoyo a la lengua, y sentirse orgulloso.<\/p>\n<p>As\u00ed pues, si est\u00e1s preparando el plan para los siguientes d\u00edas, la KORRIKA te ofrece una opci\u00f3n inmejorable. Disfrutar\u00e1 la familia, y de paso le daremos un nuevo impulso al euskera. Harrotu Korrikarekin!<\/p>\n<div class=\"st-responsive-embed\"><iframe loading=\"lazy\" title=\"HARRO HERRI (23.KORRIKAren abestia eta bideoklipa)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/wXRJVFng4Ug?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>\u00a9 ERA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ni\u00f1as, ni\u00f1os, j\u00f3venes, hijos, hijas, madres, padres, abuelas, abuelos, conocidos, desconocidas, amigas, vecinas\u2026 en la KORRIKA hay sitio para todos. Entre todos aupar\u00e1n la carrera kil\u00f3metro a kil\u00f3metro hasta llegar a Baiona. Como es bien sabido, la Korrika es una iniciativa multitudinaria a favor del euskera, plena de emoci\u00f3n y completamente participativa. Desde que se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":46656,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-46567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-al-salir"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/46567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/comments?post=46567"}],"version-history":[{"count":0,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/46567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media\/46656"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=46567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/categories?post=46567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/tags?post=46567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}