{"id":49119,"date":"2024-09-19T08:00:17","date_gmt":"2024-09-19T06:00:17","guid":{"rendered":"https:\/\/eranafarroa.eus\/?p=49119"},"modified":"2024-09-18T13:52:34","modified_gmt":"2024-09-18T11:52:34","slug":"era-boletin-redes-sociales-y-mucho-mas","status":"publish","type":"post","link":"https:\/\/eranafarroa.eus\/es\/era-boletin-redes-sociales-y-mucho-mas\/","title":{"rendered":"ERA: bolet\u00edn, redes sociales y mucho m\u00e1s"},"content":{"rendered":"<p><span style=\"font-size: 18px;\"><a href=\"https:\/\/eranafarroa.eus\/\" target=\"_blank\" rel=\"noopener\"><b>Eranafarroa<\/b><\/a><b> publica alrededor de cuatro art\u00edculos mensuales, cada jueves, con consejos, curiosidades, novedades, recursos, cultura&#8230; y todo con el objetivo de ayudar a madres y padres con hijos e hijas de 0 a 12 a\u00f1os a completar su proceso de aprendizaje del euskera.<\/b><\/span><\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #d1d1cd;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\"><strong>Suscr\u00edbete al newsletter y recibe mensualmente los art\u00edculos de ERA<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Una vez al mes recibir\u00e1s los art\u00edculos en tu correo electr\u00f3nico y as\u00ed podr\u00e1s verlos c\u00f3modamente y de un vistazo, as\u00ed como leer aquellos que te resulten m\u00e1s interesantes. Suscribirse al bolet\u00edn es muy f\u00e1cil (<a href=\"https:\/\/eus.us17.list-manage.com\/subscribe?u=c26c4b31af6ee15a30f68108d&amp;id=2f8601e66f\" target=\"_blank\" rel=\"noopener nofollow\">aqu\u00ed<\/a>), as\u00ed como cancelar la suscripci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28490 aligncenter\" src=\"https:\/\/eranafarroa.eus\/wp-content\/uploads\/2021\/11\/Suscribete-al-newsletter.gif\" alt=\"Suscr\u00edbete al bolet\u00edn de ERA\" width=\"300\" height=\"150\" \/><\/p>\n<p>&nbsp;<\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #d1d1cd;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\"><strong>Con\u00e9ctate a las redes<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>El bolet\u00edn recoge el art\u00edculo semanal, pero eranafarroa.eus ofrece mucho m\u00e1s: excursiones para disfrutar con los ni\u00f1os y ni\u00f1as, cuentos, m\u00fasica y otros recursos, art\u00edculos, v\u00eddeos, agenda cultural&#8230; Adem\u00e1s podr\u00e1s informarte de todo ello m\u00e1s a menudo a trav\u00e9s de nuestras redes sociales:\u00a0 <a href=\"https:\/\/www.instagram.com\/eranafarroa\/\" target=\"_blank\" rel=\"noopener nofollow\">Instagram<\/a>, <a href=\"https:\/\/www.facebook.com\/eranafarroa\/\" target=\"_blank\" rel=\"noopener nofollow\">Facebook<\/a> y <a href=\"https:\/\/twitter.com\/eranafarroa\" target=\"_blank\" rel=\"noopener nofollow\">X (Twitter)<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #d1d1cd;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\"><strong>No te pierdas un estreno, <a href=\"https:\/\/www.youtube.com\/@EraNafarroa\/\" target=\"_blank\" rel=\"noopener nofollow\">s\u00edguenos en YouTube<\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Nuestro canal dispone de 140 v\u00eddeos publicados: <em>ERA Eskolak<\/em>, <em>Jolasak eta Solasak<\/em> (videos para aprender a jugar en euskera con nuestras hijas e hijos), y varias listas sobre m\u00fasica, cuentos, directos, canciones para diversos momentos (cumplea\u00f1os, rutinas del hogar,\u00a0 para dormir&#8230;). \u00a1Suscribete y no te pierdas ning\u00fan estreno!<\/p>\n<p><i>\u00a9 ERA<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eranafarroa publica alrededor de cuatro art\u00edculos mensuales, cada jueves, con consejos, curiosidades, novedades, recursos, cultura&#8230; y todo con el objetivo de ayudar a madres y padres con hijos e hijas de 0 a 12 a\u00f1os a completar su proceso de aprendizaje del euskera. Suscr\u00edbete al newsletter y recibe mensualmente los art\u00edculos de ERA Una vez [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":49113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[485,486,141],"class_list":["post-49119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recursos","tag-redes-sociales","tag-suscripcion-boletin","tag-tiempolibre"],"_links":{"self":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/49119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/comments?post=49119"}],"version-history":[{"count":0,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/posts\/49119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media\/49113"}],"wp:attachment":[{"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/media?parent=49119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/categories?post=49119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eranafarroa.eus\/es\/wp-json\/wp\/v2\/tags?post=49119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}